{"id":106769,"date":"2020-10-28T21:49:51","date_gmt":"2020-10-28T20:49:51","guid":{"rendered":"http:\/\/fr.motocrossmag.be\/?p=106769"},"modified":"2020-10-28T21:49:51","modified_gmt":"2020-10-28T20:49:51","slug":"les-circuits-dentrainement-fermes","status":"publish","type":"post","link":"https:\/\/fr.motocrossmag.be\/index.php\/2020\/10\/les-circuits-dentrainement-fermes\/","title":{"rendered":"Les circuits d&rsquo;entra\u00eenement ferm\u00e9s"},"content":{"rendered":"<p><strong>A partir de ce soir, de nouvelles mesures de lutte contre le coronavirus entrent en application en Flandre. Ces mesures impacteront toutes les infrastructures sportives, qui ne seront d\u00e8s demain plus accessibles aux plus de 12 ans. Les circuits d&rsquo;entra\u00eenement de motocross ne feront pas exception.<\/strong><\/p>\n<p>\u00ab\u00a0Ce matin encore, nous \u00e9tions en discussion avec Motorsport Vlaanderen\u00a0\u00bb, explique Jef Leysen, du MC Lille. \u00ab\u00a0Ils ont travaill\u00e9 \u00e9troitement avec Sport Vlaanderen mais la conclusion est que nous devons \u00e9galement fermer. Et ouvrir uniquement pour les jeunes pilotes est tr\u00e8s difficile en pratique. Ensemble, nous avons un d\u00e9fi de taille \u00e0 relever, le monde du sport doit \u00e9galement contribuer \u00e0 l&rsquo;effort collectif.\u00a0\u00bb<\/p>\n<p>Une date \u00e0 laquelle ces mesures pourraient prendre fin n&rsquo;a pas encore \u00e9t\u00e9 \u00e9voqu\u00e9e. Elle reste de toute fa\u00e7on tr\u00e8s al\u00e9atoire puisqu&rsquo;elle d\u00e9pendra avant tout de l\u00a0\u00bb\u00e9volution de l&rsquo;\u00e9pid\u00e9mie.<\/p>\n<p>La moto de loisir sur route ouverte est en revanche toujours possible pour autant que vous ne rouliez pas en groupe de plus de 4 personnes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir de ce soir, de nouvelles mesures de lutte contre le coronavirus entrent en application en Flandre. Ces mesures impacteront toutes les infrastructures sportives, qui ne seront d\u00e8s demain [&#8230;]<\/p>\n","protected":false},"author":932,"featured_media":82914,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[54,44,4,5,45,55,65],"tags":[947],"class_list":["post-106769","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite","category-kids","category-motocross","category-news","category-news-kids","category-news-actualite","category-slideshow","tag-motocross"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les circuits d&#039;entra\u00eenement ferm\u00e9s - Motocross - Enduro - Supermoto | MotocrossMag<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fr.motocrossmag.be\/index.php\/2020\/10\/les-circuits-dentrainement-fermes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les circuits d&#039;entra\u00eenement ferm\u00e9s - Motocross - Enduro - Supermoto | MotocrossMag\" \/>\n<meta property=\"og:description\" content=\"A partir de ce soir, de nouvelles mesures de lutte contre le coronavirus entrent en application en Flandre. Ces mesures impacteront toutes les infrastructures sportives, qui ne seront d\u00e8s demain [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fr.motocrossmag.be\/index.php\/2020\/10\/les-circuits-dentrainement-fermes\/\" \/>\n<meta property=\"og:site_name\" content=\"Motocross - Enduro - Supermoto | MotocrossMag\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-28T20:49:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2018\/12\/kawasaki-pro-circuit-2019-team.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"734\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"oliviere\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"oliviere\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2020\\\/10\\\/les-circuits-dentrainement-fermes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2020\\\/10\\\/les-circuits-dentrainement-fermes\\\/\"},\"author\":{\"name\":\"oliviere\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#\\\/schema\\\/person\\\/11b47143d9f755babca2c9110e03235c\"},\"headline\":\"Les circuits d&rsquo;entra\u00eenement ferm\u00e9s\",\"datePublished\":\"2020-10-28T20:49:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2020\\\/10\\\/les-circuits-dentrainement-fermes\\\/\"},\"wordCount\":182,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2020\\\/10\\\/les-circuits-dentrainement-fermes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fr.motocrossmag.be\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/kawasaki-pro-circuit-2019-team.jpg\",\"keywords\":[\"Motocross\"],\"articleSection\":[\"Actualit\u00e9\",\"Kids\",\"Motocross\",\"News\",\"News\",\"News\",\"Slideshow\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2020\\\/10\\\/les-circuits-dentrainement-fermes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2020\\\/10\\\/les-circuits-dentrainement-fermes\\\/\",\"url\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2020\\\/10\\\/les-circuits-dentrainement-fermes\\\/\",\"name\":\"Les circuits d'entra\u00eenement ferm\u00e9s - Motocross - Enduro - Supermoto | MotocrossMag\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2020\\\/10\\\/les-circuits-dentrainement-fermes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2020\\\/10\\\/les-circuits-dentrainement-fermes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fr.motocrossmag.be\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/kawasaki-pro-circuit-2019-team.jpg\",\"datePublished\":\"2020-10-28T20:49:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#\\\/schema\\\/person\\\/11b47143d9f755babca2c9110e03235c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2020\\\/10\\\/les-circuits-dentrainement-fermes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2020\\\/10\\\/les-circuits-dentrainement-fermes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2020\\\/10\\\/les-circuits-dentrainement-fermes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fr.motocrossmag.be\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/kawasaki-pro-circuit-2019-team.jpg\",\"contentUrl\":\"https:\\\/\\\/fr.motocrossmag.be\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/kawasaki-pro-circuit-2019-team.jpg\",\"width\":1200,\"height\":734},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2020\\\/10\\\/les-circuits-dentrainement-fermes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/fr.motocrossmag.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les circuits d&rsquo;entra\u00eenement ferm\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#website\",\"url\":\"https:\\\/\\\/fr.motocrossmag.be\\\/\",\"name\":\"Motocross - Enduro - Supermoto | MotocrossMag\",\"description\":\"L&#039;actualit\u00e9 du motocross, de l&#039;enduro et du Supermoto en ligne!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fr.motocrossmag.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#\\\/schema\\\/person\\\/11b47143d9f755babca2c9110e03235c\",\"name\":\"oliviere\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g\",\"caption\":\"oliviere\"},\"sameAs\":[\"http:\\\/\\\/www.motocrossmag.be\"],\"url\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/author\\\/oliviere\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les circuits d'entra\u00eenement ferm\u00e9s - Motocross - Enduro - Supermoto | MotocrossMag","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fr.motocrossmag.be\/index.php\/2020\/10\/les-circuits-dentrainement-fermes\/","og_locale":"fr_FR","og_type":"article","og_title":"Les circuits d'entra\u00eenement ferm\u00e9s - Motocross - Enduro - Supermoto | MotocrossMag","og_description":"A partir de ce soir, de nouvelles mesures de lutte contre le coronavirus entrent en application en Flandre. Ces mesures impacteront toutes les infrastructures sportives, qui ne seront d\u00e8s demain [...]","og_url":"https:\/\/fr.motocrossmag.be\/index.php\/2020\/10\/les-circuits-dentrainement-fermes\/","og_site_name":"Motocross - Enduro - Supermoto | MotocrossMag","article_published_time":"2020-10-28T20:49:51+00:00","og_image":[{"width":1200,"height":734,"url":"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2018\/12\/kawasaki-pro-circuit-2019-team.jpg","type":"image\/jpeg"}],"author":"oliviere","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"oliviere","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fr.motocrossmag.be\/index.php\/2020\/10\/les-circuits-dentrainement-fermes\/#article","isPartOf":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2020\/10\/les-circuits-dentrainement-fermes\/"},"author":{"name":"oliviere","@id":"https:\/\/fr.motocrossmag.be\/#\/schema\/person\/11b47143d9f755babca2c9110e03235c"},"headline":"Les circuits d&rsquo;entra\u00eenement ferm\u00e9s","datePublished":"2020-10-28T20:49:51+00:00","mainEntityOfPage":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2020\/10\/les-circuits-dentrainement-fermes\/"},"wordCount":182,"commentCount":0,"image":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2020\/10\/les-circuits-dentrainement-fermes\/#primaryimage"},"thumbnailUrl":"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2018\/12\/kawasaki-pro-circuit-2019-team.jpg","keywords":["Motocross"],"articleSection":["Actualit\u00e9","Kids","Motocross","News","News","News","Slideshow"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fr.motocrossmag.be\/index.php\/2020\/10\/les-circuits-dentrainement-fermes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fr.motocrossmag.be\/index.php\/2020\/10\/les-circuits-dentrainement-fermes\/","url":"https:\/\/fr.motocrossmag.be\/index.php\/2020\/10\/les-circuits-dentrainement-fermes\/","name":"Les circuits d'entra\u00eenement ferm\u00e9s - Motocross - Enduro - Supermoto | MotocrossMag","isPartOf":{"@id":"https:\/\/fr.motocrossmag.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2020\/10\/les-circuits-dentrainement-fermes\/#primaryimage"},"image":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2020\/10\/les-circuits-dentrainement-fermes\/#primaryimage"},"thumbnailUrl":"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2018\/12\/kawasaki-pro-circuit-2019-team.jpg","datePublished":"2020-10-28T20:49:51+00:00","author":{"@id":"https:\/\/fr.motocrossmag.be\/#\/schema\/person\/11b47143d9f755babca2c9110e03235c"},"breadcrumb":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2020\/10\/les-circuits-dentrainement-fermes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fr.motocrossmag.be\/index.php\/2020\/10\/les-circuits-dentrainement-fermes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/fr.motocrossmag.be\/index.php\/2020\/10\/les-circuits-dentrainement-fermes\/#primaryimage","url":"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2018\/12\/kawasaki-pro-circuit-2019-team.jpg","contentUrl":"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2018\/12\/kawasaki-pro-circuit-2019-team.jpg","width":1200,"height":734},{"@type":"BreadcrumbList","@id":"https:\/\/fr.motocrossmag.be\/index.php\/2020\/10\/les-circuits-dentrainement-fermes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/fr.motocrossmag.be\/"},{"@type":"ListItem","position":2,"name":"Les circuits d&rsquo;entra\u00eenement ferm\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/fr.motocrossmag.be\/#website","url":"https:\/\/fr.motocrossmag.be\/","name":"Motocross - Enduro - Supermoto | MotocrossMag","description":"L&#039;actualit\u00e9 du motocross, de l&#039;enduro et du Supermoto en ligne!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fr.motocrossmag.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/fr.motocrossmag.be\/#\/schema\/person\/11b47143d9f755babca2c9110e03235c","name":"oliviere","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g","caption":"oliviere"},"sameAs":["http:\/\/www.motocrossmag.be"],"url":"https:\/\/fr.motocrossmag.be\/index.php\/author\/oliviere\/"}]}},"_links":{"self":[{"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/posts\/106769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/users\/932"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/comments?post=106769"}],"version-history":[{"count":0,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/posts\/106769\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/media\/82914"}],"wp:attachment":[{"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/media?parent=106769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/categories?post=106769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/tags?post=106769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}