{"id":106825,"date":"2020-11-02T09:24:16","date_gmt":"2020-11-02T08:24:16","guid":{"rendered":"http:\/\/fr.motocrossmag.be\/?p=106825"},"modified":"2020-11-02T09:24:16","modified_gmt":"2020-11-02T08:24:16","slug":"video-le-duel-desallecairoli-a-arco-di-trento","status":"publish","type":"post","link":"https:\/\/fr.motocrossmag.be\/index.php\/2020\/11\/video-le-duel-desallecairoli-a-arco-di-trento\/","title":{"rendered":"Vid\u00e9o : le duel Desalle\/Cairoli \u00e0 Arco di Trento"},"content":{"rendered":"<p><strong>La victoire de Cl\u00e9ment Desalle en seconde manche \u00e0 Arco di Trento apr\u00e8s avoir r\u00e9sist\u00e9 \u00e0 Antonio Cairoli est l&rsquo;un des moments forts de cette fin de saison MXGP. Les deux hommes se sont livr\u00e9s un beau duel, \u00e0 revivre en images&#8230;<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><iframe class=\"lazyload\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27650%27%20height%3D%27366%27%20viewBox%3D%270%200%20650%20366%27%3E%3Crect%20width%3D%27650%27%20height%3D%27366%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.youtube.com\/embed\/j6MLSN3HpAQ\" width=\"650\" height=\"366\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La victoire de Cl\u00e9ment Desalle en seconde manche \u00e0 Arco di Trento apr\u00e8s avoir r\u00e9sist\u00e9 \u00e0 Antonio Cairoli est l&rsquo;un des moments forts de cette fin de saison MXGP. Les [&#8230;]<\/p>\n","protected":false},"author":932,"featured_media":106826,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[54,4,6,5,55,62],"tags":[119,188,947,568,1217],"class_list":["post-106825","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite","category-motocross","category-mx1mx2","category-news","category-news-actualite","category-video","tag-antonio-cairoli","tag-clement-desalle","tag-motocross","tag-mxgp","tag-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vid\u00e9o : le duel Desalle\/Cairoli \u00e0 Arco di Trento - Motocross - Enduro - Supermoto | MotocrossMag<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fr.motocrossmag.be\/index.php\/2020\/11\/video-le-duel-desallecairoli-a-arco-di-trento\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vid\u00e9o : le duel Desalle\/Cairoli \u00e0 Arco di Trento - Motocross - Enduro - Supermoto | MotocrossMag\" \/>\n<meta property=\"og:description\" content=\"La victoire de Cl\u00e9ment Desalle en seconde manche \u00e0 Arco di Trento apr\u00e8s avoir r\u00e9sist\u00e9 \u00e0 Antonio Cairoli est l&rsquo;un des moments forts de cette fin de saison MXGP. Les [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fr.motocrossmag.be\/index.php\/2020\/11\/video-le-duel-desallecairoli-a-arco-di-trento\/\" \/>\n<meta property=\"og:site_name\" content=\"Motocross - Enduro - Supermoto | MotocrossMag\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-02T08:24:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2020\/11\/DESALLE_GP16_PH_9376.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"665\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"oliviere\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"oliviere\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2020\\\/11\\\/video-le-duel-desallecairoli-a-arco-di-trento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2020\\\/11\\\/video-le-duel-desallecairoli-a-arco-di-trento\\\/\"},\"author\":{\"name\":\"oliviere\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#\\\/schema\\\/person\\\/11b47143d9f755babca2c9110e03235c\"},\"headline\":\"Vid\u00e9o : le duel Desalle\\\/Cairoli \u00e0 Arco di Trento\",\"datePublished\":\"2020-11-02T08:24:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2020\\\/11\\\/video-le-duel-desallecairoli-a-arco-di-trento\\\/\"},\"wordCount\":54,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2020\\\/11\\\/video-le-duel-desallecairoli-a-arco-di-trento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fr.motocrossmag.be\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/DESALLE_GP16_PH_9376.jpg\",\"keywords\":[\"antonio cairoli\",\"Clement Desalle\",\"Motocross\",\"MXGP\",\"vid\u00e9o\"],\"articleSection\":[\"Actualit\u00e9\",\"Motocross\",\"Motocross MXGP\",\"News\",\"News\",\"Videos\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2020\\\/11\\\/video-le-duel-desallecairoli-a-arco-di-trento\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2020\\\/11\\\/video-le-duel-desallecairoli-a-arco-di-trento\\\/\",\"url\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2020\\\/11\\\/video-le-duel-desallecairoli-a-arco-di-trento\\\/\",\"name\":\"Vid\u00e9o : le duel Desalle\\\/Cairoli \u00e0 Arco di Trento - Motocross - Enduro - Supermoto | MotocrossMag\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2020\\\/11\\\/video-le-duel-desallecairoli-a-arco-di-trento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2020\\\/11\\\/video-le-duel-desallecairoli-a-arco-di-trento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fr.motocrossmag.be\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/DESALLE_GP16_PH_9376.jpg\",\"datePublished\":\"2020-11-02T08:24:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#\\\/schema\\\/person\\\/11b47143d9f755babca2c9110e03235c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2020\\\/11\\\/video-le-duel-desallecairoli-a-arco-di-trento\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2020\\\/11\\\/video-le-duel-desallecairoli-a-arco-di-trento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2020\\\/11\\\/video-le-duel-desallecairoli-a-arco-di-trento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fr.motocrossmag.be\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/DESALLE_GP16_PH_9376.jpg\",\"contentUrl\":\"https:\\\/\\\/fr.motocrossmag.be\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/DESALLE_GP16_PH_9376.jpg\",\"width\":1000,\"height\":665},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2020\\\/11\\\/video-le-duel-desallecairoli-a-arco-di-trento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/fr.motocrossmag.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vid\u00e9o : le duel Desalle\\\/Cairoli \u00e0 Arco di Trento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#website\",\"url\":\"https:\\\/\\\/fr.motocrossmag.be\\\/\",\"name\":\"Motocross - Enduro - Supermoto | MotocrossMag\",\"description\":\"L&#039;actualit\u00e9 du motocross, de l&#039;enduro et du Supermoto en ligne!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fr.motocrossmag.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#\\\/schema\\\/person\\\/11b47143d9f755babca2c9110e03235c\",\"name\":\"oliviere\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g\",\"caption\":\"oliviere\"},\"sameAs\":[\"http:\\\/\\\/www.motocrossmag.be\"],\"url\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/author\\\/oliviere\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vid\u00e9o : le duel Desalle\/Cairoli \u00e0 Arco di Trento - Motocross - Enduro - Supermoto | MotocrossMag","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fr.motocrossmag.be\/index.php\/2020\/11\/video-le-duel-desallecairoli-a-arco-di-trento\/","og_locale":"fr_FR","og_type":"article","og_title":"Vid\u00e9o : le duel Desalle\/Cairoli \u00e0 Arco di Trento - Motocross - Enduro - Supermoto | MotocrossMag","og_description":"La victoire de Cl\u00e9ment Desalle en seconde manche \u00e0 Arco di Trento apr\u00e8s avoir r\u00e9sist\u00e9 \u00e0 Antonio Cairoli est l&rsquo;un des moments forts de cette fin de saison MXGP. Les [...]","og_url":"https:\/\/fr.motocrossmag.be\/index.php\/2020\/11\/video-le-duel-desallecairoli-a-arco-di-trento\/","og_site_name":"Motocross - Enduro - Supermoto | MotocrossMag","article_published_time":"2020-11-02T08:24:16+00:00","og_image":[{"width":1000,"height":665,"url":"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2020\/11\/DESALLE_GP16_PH_9376.jpg","type":"image\/jpeg"}],"author":"oliviere","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"oliviere"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fr.motocrossmag.be\/index.php\/2020\/11\/video-le-duel-desallecairoli-a-arco-di-trento\/#article","isPartOf":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2020\/11\/video-le-duel-desallecairoli-a-arco-di-trento\/"},"author":{"name":"oliviere","@id":"https:\/\/fr.motocrossmag.be\/#\/schema\/person\/11b47143d9f755babca2c9110e03235c"},"headline":"Vid\u00e9o : le duel Desalle\/Cairoli \u00e0 Arco di Trento","datePublished":"2020-11-02T08:24:16+00:00","mainEntityOfPage":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2020\/11\/video-le-duel-desallecairoli-a-arco-di-trento\/"},"wordCount":54,"commentCount":0,"image":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2020\/11\/video-le-duel-desallecairoli-a-arco-di-trento\/#primaryimage"},"thumbnailUrl":"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2020\/11\/DESALLE_GP16_PH_9376.jpg","keywords":["antonio cairoli","Clement Desalle","Motocross","MXGP","vid\u00e9o"],"articleSection":["Actualit\u00e9","Motocross","Motocross MXGP","News","News","Videos"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fr.motocrossmag.be\/index.php\/2020\/11\/video-le-duel-desallecairoli-a-arco-di-trento\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fr.motocrossmag.be\/index.php\/2020\/11\/video-le-duel-desallecairoli-a-arco-di-trento\/","url":"https:\/\/fr.motocrossmag.be\/index.php\/2020\/11\/video-le-duel-desallecairoli-a-arco-di-trento\/","name":"Vid\u00e9o : le duel Desalle\/Cairoli \u00e0 Arco di Trento - Motocross - Enduro - Supermoto | MotocrossMag","isPartOf":{"@id":"https:\/\/fr.motocrossmag.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2020\/11\/video-le-duel-desallecairoli-a-arco-di-trento\/#primaryimage"},"image":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2020\/11\/video-le-duel-desallecairoli-a-arco-di-trento\/#primaryimage"},"thumbnailUrl":"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2020\/11\/DESALLE_GP16_PH_9376.jpg","datePublished":"2020-11-02T08:24:16+00:00","author":{"@id":"https:\/\/fr.motocrossmag.be\/#\/schema\/person\/11b47143d9f755babca2c9110e03235c"},"breadcrumb":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2020\/11\/video-le-duel-desallecairoli-a-arco-di-trento\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fr.motocrossmag.be\/index.php\/2020\/11\/video-le-duel-desallecairoli-a-arco-di-trento\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/fr.motocrossmag.be\/index.php\/2020\/11\/video-le-duel-desallecairoli-a-arco-di-trento\/#primaryimage","url":"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2020\/11\/DESALLE_GP16_PH_9376.jpg","contentUrl":"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2020\/11\/DESALLE_GP16_PH_9376.jpg","width":1000,"height":665},{"@type":"BreadcrumbList","@id":"https:\/\/fr.motocrossmag.be\/index.php\/2020\/11\/video-le-duel-desallecairoli-a-arco-di-trento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/fr.motocrossmag.be\/"},{"@type":"ListItem","position":2,"name":"Vid\u00e9o : le duel Desalle\/Cairoli \u00e0 Arco di Trento"}]},{"@type":"WebSite","@id":"https:\/\/fr.motocrossmag.be\/#website","url":"https:\/\/fr.motocrossmag.be\/","name":"Motocross - Enduro - Supermoto | MotocrossMag","description":"L&#039;actualit\u00e9 du motocross, de l&#039;enduro et du Supermoto en ligne!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fr.motocrossmag.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/fr.motocrossmag.be\/#\/schema\/person\/11b47143d9f755babca2c9110e03235c","name":"oliviere","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g","caption":"oliviere"},"sameAs":["http:\/\/www.motocrossmag.be"],"url":"https:\/\/fr.motocrossmag.be\/index.php\/author\/oliviere\/"}]}},"_links":{"self":[{"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/posts\/106825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/users\/932"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/comments?post=106825"}],"version-history":[{"count":0,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/posts\/106825\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/media\/106826"}],"wp:attachment":[{"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/media?parent=106825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/categories?post=106825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/tags?post=106825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}