{"id":137635,"date":"2024-05-26T16:28:42","date_gmt":"2024-05-26T14:28:42","guid":{"rendered":"https:\/\/fr.motocrossmag.be\/?p=137635"},"modified":"2024-05-26T22:20:46","modified_gmt":"2024-05-26T20:20:46","slug":"espoirs-enzo-herzogenrath-simpose-sous-le-soleil-de-villars-sous-ecot","status":"publish","type":"post","link":"https:\/\/fr.motocrossmag.be\/index.php\/2024\/05\/espoirs-enzo-herzogenrath-simpose-sous-le-soleil-de-villars-sous-ecot\/","title":{"rendered":"Espoirs : Enzo Herzogenrath s&rsquo;impose sous le soleil de Villars-sous-Ecot"},"content":{"rendered":"<p><strong>Une piste bien pr\u00e9par\u00e9e et un grand soleil : voici les conditions dans lesquelles se sont affront\u00e9s les pilotes du 24MX tour espoir du c\u00f4t\u00e9 de Villars-sous-\u00c9cot. En l\u2019absence des deux leaders du championnat retenus pour une \u00e9preuve d\u2019Europe, Enzo Herzogenrath (2\/1), Kenzo Ferez (1\/2) et Wesley Suteau (4\/4) ont parfaitement profit\u00e9 de l\u2019occasion pour monter sur le podium dans cet ordre. On retrouvera tout ce beau monde le quinze juin prochain pour la finale d\u2019Ern\u00e9e.<\/strong><\/p>\n<p>Trois semaines apr\u00e8s l\u2019\u00e9preuve de Bitche, les jeunes pilotes du 24MX Tour espoir se sont retrouv\u00e9s derri\u00e8re la grille de Villars-sous-\u00c9cot pour disputer leur cinqui\u00e8me \u00e9preuve de la saison. Retenus sur une course de qualification de\u00a0championnat d\u2019Europe 85 cm3, L\u00e9o Diss-Fenard (leader du championnat), Sleny Goyer (P2) et Rafael Mennillo (P4) n\u2019\u00e9taient pas de la partie. Notez que ces gar\u00e7ons b\u00e9n\u00e9ficieront d\u2019un report de points en fin de saison.<\/p>\n<p>D\u00e9j\u00e0 vainqueur d\u2019une manche \u00e0 Castelnau-de-L\u00e9vis il y a quelques semaines, Kenzo Ferez s\u2019est offert le meilleur d\u00e9part du premier d\u00e9bat avant de creuser l\u2019\u00e9cart et de s\u2019imposer avec une marge d\u2019un peu moins de cinq secondes. En t\u00eate de bout en bout, le jeune pilote KTM a tr\u00e8s bien su g\u00e9rer cette premi\u00e8re manche du week-end. De retour en forme apr\u00e8s une blessure en d\u00e9but d\u2019ann\u00e9e, Enzo Herzogenrath a bien roul\u00e9 lui aussi en s\u2019offrant la seconde place, son meilleur r\u00e9sultat de la saison.<\/p>\n<p>En bagarre pour la victoire durant plusieurs tours,\u00a0le jeune\u00a0Loan Torro a lui aussi fait forte impression en montant pour la premi\u00e8re fois sur un podium de manche du 24MX Tour espoir (P3), en d\u00e9pit d\u2019une petite chute. Solide quatri\u00e8me, Wesley Suteau termine devant Leny Muller et Arno Cazet.<\/p>\n<p><strong>Premi\u00e8re pour Herzogenrath\u00a0!<\/strong><\/p>\n<p>Au second d\u00e9part, c\u2019est Enzo Herzogenrath qui s\u2019\u00e9lance en t\u00eate avec sur ses talons Kenzo Ferez, Arno Cazet, Wesley Suteau et Loan Torro. Les hommes forts de la premi\u00e8re manche se retrouvent une fois de plus aux avant-postes. Impressionnant d\u2019attaque, le jeune pilote TMX Comp\u00e9tition tient le choc, finit par creuser l\u2019\u00e9cart et remporte sa manche sur le 24MX Tour \u00e0 seulement douze ans.<\/p>\n<p>Derri\u00e8re lui, Ferez terminent en seconde position devant un tr\u00e8s bon Cazet, un solide Suteau et Aaron Cornet qui compl\u00e8te le top cinq. Sur le podium de la premi\u00e8re manche, Torro est contraint \u00e0 l\u2019abandon et rentre au paddock avant de voir le drapeau \u00e0 damiers. Actuel quatri\u00e8me du Minivert minime, Enzo Herzogenrath signe la performance de la journ\u00e9e en s\u2019imposant pour la premi\u00e8re fois chez les espoirs (2\/1).<\/p>\n<p>Avec le m\u00eame nombre de point (1\/2), mais une moins bonne seconde manche, Ferez monte sur la seconde marche du podium (1\/2). La r\u00e9gularit\u00e9 paie pour Wesley Suteau (4\/4) qui termine troisi\u00e8me du g\u00e9n\u00e9ral, un point devant Arno Cazet (6\/3).\u00a0Pour finir, sachez que c\u2019est Kenzo Ferez qui abordera la derni\u00e8re course de la saison avec la plaque rouge, en attendant la validation du report de points des pilotes engag\u00e9s sur l\u2019Europe.<\/p>\n<p>Rendez-vous \u00e0 Ern\u00e9e !<\/p>\n<hr \/>\n<p><span style=\"color: #ff0000;\"><strong>R\u00e9sum\u00e9 vid\u00e9o<\/strong><\/span><\/p>\n<div class=\"su-youtube su-u-responsive-media-yes\"><iframe class=\"lazyload\" width=\"640\" height=\"400\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27640%27%20height%3D%27400%27%20viewBox%3D%270%200%20640%20400%27%3E%3Crect%20width%3D%27640%27%20height%3D%27400%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.youtube.com\/embed\/qlVk83WopO4?\" frameborder=\"0\" allowfullscreen allow=\"autoplay; encrypted-media; picture-in-picture\" title=\"\"><\/iframe><\/div>\n<hr \/>\n<p><span style=\"color: #800000;\"><strong>R\u00e9sultats<\/strong><\/span><\/p>\n<p>1 HERZOGENRATH Enzo KTM 22+25<br \/>\n2 FEREZ Kenzo KTM 25+22<br \/>\n3 SUTEAU Wesley KTM 18+18<br \/>\n4 CAZET Arno Gas Gas\u00a0 15+20<br \/>\n5 CORNET Aaron KTM P13+16<br \/>\n6 BEURET Jules GasGas 14+14<br \/>\n7 BONNET Ewan GasGas 12+12<br \/>\n8 ANGELVIN Matheo Husqvarna 9+13<br \/>\n9 STEFANI Emilio KTM 11+10<br \/>\n10 TORRO Loan GasGas 20+0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une piste bien pr\u00e9par\u00e9e et un grand soleil : voici les conditions dans lesquelles se sont affront\u00e9s les pilotes du 24MX tour espoir du c\u00f4t\u00e9 de Villars-sous-\u00c9cot. En l\u2019absence des [&#8230;]<\/p>\n","protected":false},"author":932,"featured_media":137636,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[54,44,4,5,45,55,56,65],"tags":[486,947,522],"class_list":["post-137635","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite","category-kids","category-motocross","category-news","category-news-kids","category-news-actualite","category-resultats","category-slideshow","tag-elite","tag-motocross","tag-villars-sous-ecot"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Espoirs : Enzo Herzogenrath s&#039;impose sous le soleil de Villars-sous-Ecot - Motocross - Enduro - Supermoto | MotocrossMag<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fr.motocrossmag.be\/index.php\/2024\/05\/espoirs-enzo-herzogenrath-simpose-sous-le-soleil-de-villars-sous-ecot\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Espoirs : Enzo Herzogenrath s&#039;impose sous le soleil de Villars-sous-Ecot - Motocross - Enduro - Supermoto | MotocrossMag\" \/>\n<meta property=\"og:description\" content=\"Une piste bien pr\u00e9par\u00e9e et un grand soleil : voici les conditions dans lesquelles se sont affront\u00e9s les pilotes du 24MX tour espoir du c\u00f4t\u00e9 de Villars-sous-\u00c9cot. En l\u2019absence des [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fr.motocrossmag.be\/index.php\/2024\/05\/espoirs-enzo-herzogenrath-simpose-sous-le-soleil-de-villars-sous-ecot\/\" \/>\n<meta property=\"og:site_name\" content=\"Motocross - Enduro - Supermoto | MotocrossMag\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-26T14:28:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-26T20:20:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-25-at-11.24.06.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"oliviere\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"oliviere\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2024\\\/05\\\/espoirs-enzo-herzogenrath-simpose-sous-le-soleil-de-villars-sous-ecot\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2024\\\/05\\\/espoirs-enzo-herzogenrath-simpose-sous-le-soleil-de-villars-sous-ecot\\\/\"},\"author\":{\"name\":\"oliviere\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#\\\/schema\\\/person\\\/11b47143d9f755babca2c9110e03235c\"},\"headline\":\"Espoirs : Enzo Herzogenrath s&rsquo;impose sous le soleil de Villars-sous-Ecot\",\"datePublished\":\"2024-05-26T14:28:42+00:00\",\"dateModified\":\"2024-05-26T20:20:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2024\\\/05\\\/espoirs-enzo-herzogenrath-simpose-sous-le-soleil-de-villars-sous-ecot\\\/\"},\"wordCount\":611,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2024\\\/05\\\/espoirs-enzo-herzogenrath-simpose-sous-le-soleil-de-villars-sous-ecot\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fr.motocrossmag.be\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/WhatsApp-Image-2024-05-25-at-11.24.06.jpeg\",\"keywords\":[\"Elite\",\"Motocross\",\"villars sous ecot\"],\"articleSection\":[\"Actualit\u00e9\",\"Kids\",\"Motocross\",\"News\",\"News\",\"News\",\"R\u00e9sultats\",\"Slideshow\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2024\\\/05\\\/espoirs-enzo-herzogenrath-simpose-sous-le-soleil-de-villars-sous-ecot\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2024\\\/05\\\/espoirs-enzo-herzogenrath-simpose-sous-le-soleil-de-villars-sous-ecot\\\/\",\"url\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2024\\\/05\\\/espoirs-enzo-herzogenrath-simpose-sous-le-soleil-de-villars-sous-ecot\\\/\",\"name\":\"Espoirs : Enzo Herzogenrath s'impose sous le soleil de Villars-sous-Ecot - Motocross - Enduro - Supermoto | MotocrossMag\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2024\\\/05\\\/espoirs-enzo-herzogenrath-simpose-sous-le-soleil-de-villars-sous-ecot\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2024\\\/05\\\/espoirs-enzo-herzogenrath-simpose-sous-le-soleil-de-villars-sous-ecot\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fr.motocrossmag.be\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/WhatsApp-Image-2024-05-25-at-11.24.06.jpeg\",\"datePublished\":\"2024-05-26T14:28:42+00:00\",\"dateModified\":\"2024-05-26T20:20:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#\\\/schema\\\/person\\\/11b47143d9f755babca2c9110e03235c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2024\\\/05\\\/espoirs-enzo-herzogenrath-simpose-sous-le-soleil-de-villars-sous-ecot\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2024\\\/05\\\/espoirs-enzo-herzogenrath-simpose-sous-le-soleil-de-villars-sous-ecot\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2024\\\/05\\\/espoirs-enzo-herzogenrath-simpose-sous-le-soleil-de-villars-sous-ecot\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fr.motocrossmag.be\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/WhatsApp-Image-2024-05-25-at-11.24.06.jpeg\",\"contentUrl\":\"https:\\\/\\\/fr.motocrossmag.be\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/WhatsApp-Image-2024-05-25-at-11.24.06.jpeg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2024\\\/05\\\/espoirs-enzo-herzogenrath-simpose-sous-le-soleil-de-villars-sous-ecot\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/fr.motocrossmag.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Espoirs : Enzo Herzogenrath s&rsquo;impose sous le soleil de Villars-sous-Ecot\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#website\",\"url\":\"https:\\\/\\\/fr.motocrossmag.be\\\/\",\"name\":\"Motocross - Enduro - Supermoto | MotocrossMag\",\"description\":\"L&#039;actualit\u00e9 du motocross, de l&#039;enduro et du Supermoto en ligne!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fr.motocrossmag.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#\\\/schema\\\/person\\\/11b47143d9f755babca2c9110e03235c\",\"name\":\"oliviere\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g\",\"caption\":\"oliviere\"},\"sameAs\":[\"http:\\\/\\\/www.motocrossmag.be\"],\"url\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/author\\\/oliviere\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Espoirs : Enzo Herzogenrath s'impose sous le soleil de Villars-sous-Ecot - Motocross - Enduro - Supermoto | MotocrossMag","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fr.motocrossmag.be\/index.php\/2024\/05\/espoirs-enzo-herzogenrath-simpose-sous-le-soleil-de-villars-sous-ecot\/","og_locale":"fr_FR","og_type":"article","og_title":"Espoirs : Enzo Herzogenrath s'impose sous le soleil de Villars-sous-Ecot - Motocross - Enduro - Supermoto | MotocrossMag","og_description":"Une piste bien pr\u00e9par\u00e9e et un grand soleil : voici les conditions dans lesquelles se sont affront\u00e9s les pilotes du 24MX tour espoir du c\u00f4t\u00e9 de Villars-sous-\u00c9cot. En l\u2019absence des [...]","og_url":"https:\/\/fr.motocrossmag.be\/index.php\/2024\/05\/espoirs-enzo-herzogenrath-simpose-sous-le-soleil-de-villars-sous-ecot\/","og_site_name":"Motocross - Enduro - Supermoto | MotocrossMag","article_published_time":"2024-05-26T14:28:42+00:00","article_modified_time":"2024-05-26T20:20:46+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-25-at-11.24.06.jpeg","type":"image\/jpeg"}],"author":"oliviere","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"oliviere","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fr.motocrossmag.be\/index.php\/2024\/05\/espoirs-enzo-herzogenrath-simpose-sous-le-soleil-de-villars-sous-ecot\/#article","isPartOf":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2024\/05\/espoirs-enzo-herzogenrath-simpose-sous-le-soleil-de-villars-sous-ecot\/"},"author":{"name":"oliviere","@id":"https:\/\/fr.motocrossmag.be\/#\/schema\/person\/11b47143d9f755babca2c9110e03235c"},"headline":"Espoirs : Enzo Herzogenrath s&rsquo;impose sous le soleil de Villars-sous-Ecot","datePublished":"2024-05-26T14:28:42+00:00","dateModified":"2024-05-26T20:20:46+00:00","mainEntityOfPage":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2024\/05\/espoirs-enzo-herzogenrath-simpose-sous-le-soleil-de-villars-sous-ecot\/"},"wordCount":611,"commentCount":0,"image":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2024\/05\/espoirs-enzo-herzogenrath-simpose-sous-le-soleil-de-villars-sous-ecot\/#primaryimage"},"thumbnailUrl":"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-25-at-11.24.06.jpeg","keywords":["Elite","Motocross","villars sous ecot"],"articleSection":["Actualit\u00e9","Kids","Motocross","News","News","News","R\u00e9sultats","Slideshow"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fr.motocrossmag.be\/index.php\/2024\/05\/espoirs-enzo-herzogenrath-simpose-sous-le-soleil-de-villars-sous-ecot\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fr.motocrossmag.be\/index.php\/2024\/05\/espoirs-enzo-herzogenrath-simpose-sous-le-soleil-de-villars-sous-ecot\/","url":"https:\/\/fr.motocrossmag.be\/index.php\/2024\/05\/espoirs-enzo-herzogenrath-simpose-sous-le-soleil-de-villars-sous-ecot\/","name":"Espoirs : Enzo Herzogenrath s'impose sous le soleil de Villars-sous-Ecot - Motocross - Enduro - Supermoto | MotocrossMag","isPartOf":{"@id":"https:\/\/fr.motocrossmag.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2024\/05\/espoirs-enzo-herzogenrath-simpose-sous-le-soleil-de-villars-sous-ecot\/#primaryimage"},"image":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2024\/05\/espoirs-enzo-herzogenrath-simpose-sous-le-soleil-de-villars-sous-ecot\/#primaryimage"},"thumbnailUrl":"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-25-at-11.24.06.jpeg","datePublished":"2024-05-26T14:28:42+00:00","dateModified":"2024-05-26T20:20:46+00:00","author":{"@id":"https:\/\/fr.motocrossmag.be\/#\/schema\/person\/11b47143d9f755babca2c9110e03235c"},"breadcrumb":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2024\/05\/espoirs-enzo-herzogenrath-simpose-sous-le-soleil-de-villars-sous-ecot\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fr.motocrossmag.be\/index.php\/2024\/05\/espoirs-enzo-herzogenrath-simpose-sous-le-soleil-de-villars-sous-ecot\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/fr.motocrossmag.be\/index.php\/2024\/05\/espoirs-enzo-herzogenrath-simpose-sous-le-soleil-de-villars-sous-ecot\/#primaryimage","url":"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-25-at-11.24.06.jpeg","contentUrl":"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-25-at-11.24.06.jpeg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/fr.motocrossmag.be\/index.php\/2024\/05\/espoirs-enzo-herzogenrath-simpose-sous-le-soleil-de-villars-sous-ecot\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/fr.motocrossmag.be\/"},{"@type":"ListItem","position":2,"name":"Espoirs : Enzo Herzogenrath s&rsquo;impose sous le soleil de Villars-sous-Ecot"}]},{"@type":"WebSite","@id":"https:\/\/fr.motocrossmag.be\/#website","url":"https:\/\/fr.motocrossmag.be\/","name":"Motocross - Enduro - Supermoto | MotocrossMag","description":"L&#039;actualit\u00e9 du motocross, de l&#039;enduro et du Supermoto en ligne!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fr.motocrossmag.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/fr.motocrossmag.be\/#\/schema\/person\/11b47143d9f755babca2c9110e03235c","name":"oliviere","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g","caption":"oliviere"},"sameAs":["http:\/\/www.motocrossmag.be"],"url":"https:\/\/fr.motocrossmag.be\/index.php\/author\/oliviere\/"}]}},"_links":{"self":[{"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/posts\/137635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/users\/932"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/comments?post=137635"}],"version-history":[{"count":1,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/posts\/137635\/revisions"}],"predecessor-version":[{"id":137637,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/posts\/137635\/revisions\/137637"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/media\/137636"}],"wp:attachment":[{"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/media?parent=137635"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/categories?post=137635"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/tags?post=137635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}