{"id":151709,"date":"2025-10-02T12:27:23","date_gmt":"2025-10-02T10:27:23","guid":{"rendered":"https:\/\/fr.motocrossmag.be\/?p=151709"},"modified":"2025-10-02T12:27:23","modified_gmt":"2025-10-02T10:27:23","slug":"interview-liam-everts-et-les-freres-coenen-prets-a-se-battre-pour-briller-sur-le-mx-des-nations-aux-usa","status":"publish","type":"post","link":"https:\/\/fr.motocrossmag.be\/index.php\/2025\/10\/interview-liam-everts-et-les-freres-coenen-prets-a-se-battre-pour-briller-sur-le-mx-des-nations-aux-usa\/","title":{"rendered":"Interview &#8211; Liam Everts et les fr\u00e8res Coenen pr\u00eats \u00e0 se battre pour briller sur le MX des Nations aux USA"},"content":{"rendered":"<p>Ce week-end, le Team Belgium sera aux \u00c9tats-Unis pour y affronter le reste du monde sur le Motocross des Nations, disput\u00e9 cette ann\u00e9e \u00e0 Crawfordsville (Indiana). Lucas Coenen, vice-champion du monde MXGP, son fr\u00e8re jumeau Sacha (MX2) et Liam Everts (Open) visent un podium face \u00e0 l\u2019\u00e9lite mondiale. Entre ambitions, bilan de saison et r\u00eaves am\u00e9ricains, les trois pilotes se confient.<\/p>\n<p><a href=\"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2025\/10\/SI202507302974.avif\"><img decoding=\"async\" class=\"alignnone size-full wp-image-151713\" src=\"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2025\/10\/SI202507302974.avif\" alt=\"\" width=\"1200\" height=\"800\" \/><\/a><\/p><div class=\"mrpbv6a97a3cd49a96\" ><!-- \/91277017\/Inline-articles-mobile -->\n<div style=\"margin:auto; text-align:center !important\">\n<div id='div-gpt-ad-1784982661365-0' style='min-width: 250px; min-height: 75px;'>\n  <script>\n    googletag.cmd.push(function() { googletag.display('div-gpt-ad-1784982661365-0'); });\n  <\/script>\n<\/div><\/div><\/div><style type=\"text\/css\">\r\n.mrpbv6a97a3cd49a96 {\r\nmargin-bottom:30px;margin-top:20px\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.mrpbv6a97a3cd49a96 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.mrpbv6a97a3cd49a96 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.mrpbv6a97a3cd49a96 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.mrpbv6a97a3cd49a96 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.mrpbv6a97a3cd49a96 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n\n<p><strong>La motivation est-elle toujours au rendez-vous apr\u00e8s une saison aussi intens<\/strong>e ?<\/p>\n<p>Lucas Coenen : Absolument. M\u00eame en Australie, quand le titre mondial \u00e9tait hors de port\u00e9e, j\u2019ai donn\u00e9 le maximum. J\u2019ai toujours cette envie : \u00eatre le meilleur. Et il y a toujours des choses \u00e0 am\u00e9liorer. Aller aux \u00c9tats-Unis va encore me faire progresser.<\/p>\n<p>Liam Everts : Je suis vraiment impatient. Je me sens pr\u00eat, et nous avons une \u00e9quipe solide.<\/p><div class=\"zrwok6a97a3cd49aab\" ><!-- \/91277017\/articles-inline-2 -->\n<div style=\"margin: 20px auto; text-align:center !important\">\n<div id='div-gpt-ad-1785021530385-0' style='min-width: 300px; min-height: 75px;'>\n  <script>\n    googletag.cmd.push(function() { googletag.display('div-gpt-ad-1785021530385-0'); });\n  <\/script>\n<\/div><\/div><\/div><style type=\"text\/css\">\r\n@media screen and (min-width: 1201px) {\r\n.zrwok6a97a3cd49aab {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.zrwok6a97a3cd49aab {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.zrwok6a97a3cd49aab {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.zrwok6a97a3cd49aab {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.zrwok6a97a3cd49aab {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n\n<p><a href=\"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2025\/10\/SI202503160289.avif\"><img decoding=\"async\" class=\"alignnone size-full wp-image-151712\" src=\"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2025\/10\/SI202503160289.avif\" alt=\"\" width=\"1200\" height=\"800\" \/><\/a><\/p>\n<p><strong>Comment r\u00e9sumez-vous votre saison 2025 ?<\/strong><\/p>\n<p>Sacha Coenen : Elle a \u00e9t\u00e9 bonne, avec quelques hauts et quelques bas. Nous avons presque toujours \u00e9t\u00e9 sur le podium, et j\u2019ai quasiment tout gagn\u00e9 lors des trois derni\u00e8res courses. Je suis satisfait, m\u00eame si on peut toujours faire mieux.<\/p>\n<p>Lucas Coenen : Je suis content de ma saison. Mes poignets m\u2019ont pos\u00e9 probl\u00e8me au d\u00e9but, mais j\u2019ai quand m\u00eame remport\u00e9 six Grands Prix. Le titre m\u2019a \u00e9chapp\u00e9, mais je sais ce que j\u2019ai mal fait\u2026 pas grand-chose.<\/p>\n<p>Liam Everts : Ce n\u2019\u00e9tait pas facile. Je revenais d\u2019une grosse blessure de 2024 et j\u2019ai encore chut\u00e9 en Finlande. Il y a eu des hauts et des bas. Ma derni\u00e8re course m\u2019a donn\u00e9 satisfaction, mais le r\u00e9sultat final ne l\u2019a pas refl\u00e9t\u00e9.<\/p>\n<p><a href=\"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2025\/08\/SI202508170539.jpg\"><img decoding=\"async\" class=\"size-full wp-image-150339\" src=\"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2025\/08\/SI202508170539.jpg\" alt=\"\" width=\"1200\" height=\"800\" srcset=\"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2025\/08\/SI202508170539.jpg 1200w, https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2025\/08\/SI202508170539-650x433.jpg 650w, https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2025\/08\/SI202508170539-1024x683.jpg 1024w, https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2025\/08\/SI202508170539-768x512.jpg 768w, https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2025\/08\/SI202508170539-200x133.jpg 200w, https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2025\/08\/SI202508170539-400x267.jpg 400w, https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2025\/08\/SI202508170539-600x400.jpg 600w, https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2025\/08\/SI202508170539-800x533.jpg 800w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a><\/p>\n<p><strong>Quelles ambitions pour le MXoN ?<\/strong><\/p>\n<p>Lucas Coenen : Nous avons une \u00e9quipe solide et partons avec ambition. Sacha et moi sommes en forme, Liam aussi. Nous avons la vitesse et la r\u00e9gularit\u00e9 n\u00e9cessaires pour un bon r\u00e9sultat global. Et puis, courir aux \u00c9tats-Unis, c\u2019est g\u00e9nial.<\/p>\n<p>Liam Everts : Je veux briller dans la cat\u00e9gorie Open. C\u2019est ma premi\u00e8re course sur une 450, donc c\u2019est un vrai d\u00e9fi. Si tout le monde est concentr\u00e9, nous pouvons viser un tr\u00e8s beau r\u00e9sultat.<\/p>\n<p>Sacha Coenen : Nous avons un bon trio. Le podium serait fantastique. J\u2019ai vraiment h\u00e2te : c\u2019est une course magnifique, avec beaucoup de fans et une piste superbe. Courir aux \u00c9tats-Unis est un r\u00eave pour moi.<\/p>\n<p><a href=\"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2025\/10\/SI202505250504.avif\"><img decoding=\"async\" class=\"alignnone size-full wp-image-151710\" src=\"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2025\/10\/SI202505250504.avif\" alt=\"\" width=\"1200\" height=\"800\" \/><\/a><\/p>\n<p><strong>Et apr\u00e8s le MXoN ?<\/strong><\/p>\n<p>Sacha Coenen : Nous resterons trois semaines aux \u00c9tats-Unis pour nous entra\u00eener, tester et profiter un peu. Ensuite, deux semaines de vacances : golf, moto, tennis, sport entre amis\u2026 du plaisir avant la prochaine saison.<\/p>\n<p>Lucas Coenen : Repos, football, tennis, golf\u2026 mais on continue toujours \u00e0 s\u2019entra\u00eener \u00e0 moto pour rester performants.<\/p>\n<p>Liam Everts : Retour \u00e0 la maison, puis deux petites courses encore. On est pr\u00eats \u00e0 relever le d\u00e9fi !<\/p>\n<p>Photos : RedBull Content Pool<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce week-end, le Team Belgium sera aux \u00c9tats-Unis pour y affronter le reste du monde sur le Motocross des Nations, disput\u00e9 cette ann\u00e9e \u00e0 Crawfordsville (Indiana). Lucas Coenen, vice-champion du monde MXGP, son fr\u00e8re jumeau Sacha (MX2) et Liam Everts (Open) visent un podium face \u00e0 l\u2019\u00e9lite mondiale. Entre ambitions, bilan de saison et r\u00eaves [&hellip;]<\/p>\n","protected":false},"author":932,"featured_media":151711,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[54,7,58,4,6,74,5,55,65],"tags":[1247,1265,947,291,1171,568,1471],"class_list":["post-151709","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualite","category-interviews","category-interviews-actualite","category-motocross","category-mx1mx2","category-mx-des-nations","category-news","category-news-actualite","category-slideshow","tag-liam-everts","tag-lucas-coenen","tag-motocross","tag-motocross-des-nations","tag-mxdn","tag-mxgp","tag-sacha-coenen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Interview - Liam Everts et les fr\u00e8res Coenen pr\u00eats \u00e0 se battre pour briller sur le MX des Nations aux USA - Motocross - Enduro - Supermoto | MotocrossMag<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fr.motocrossmag.be\/index.php\/2025\/10\/interview-liam-everts-et-les-freres-coenen-prets-a-se-battre-pour-briller-sur-le-mx-des-nations-aux-usa\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Interview - Liam Everts et les fr\u00e8res Coenen pr\u00eats \u00e0 se battre pour briller sur le MX des Nations aux USA - Motocross - Enduro - Supermoto | MotocrossMag\" \/>\n<meta property=\"og:description\" content=\"Ce week-end, le Team Belgium sera aux \u00c9tats-Unis pour y affronter le reste du monde sur le Motocross des Nations, disput\u00e9 cette ann\u00e9e \u00e0 Crawfordsville (Indiana). Lucas Coenen, vice-champion du monde MXGP, son fr\u00e8re jumeau Sacha (MX2) et Liam Everts (Open) visent un podium face \u00e0 l\u2019\u00e9lite mondiale. Entre ambitions, bilan de saison et r\u00eaves [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fr.motocrossmag.be\/index.php\/2025\/10\/interview-liam-everts-et-les-freres-coenen-prets-a-se-battre-pour-briller-sur-le-mx-des-nations-aux-usa\/\" \/>\n<meta property=\"og:site_name\" content=\"Motocross - Enduro - Supermoto | MotocrossMag\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-02T10:27:23+00:00\" \/>\n<meta name=\"author\" content=\"oliviere\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"oliviere\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2025\\\/10\\\/interview-liam-everts-et-les-freres-coenen-prets-a-se-battre-pour-briller-sur-le-mx-des-nations-aux-usa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2025\\\/10\\\/interview-liam-everts-et-les-freres-coenen-prets-a-se-battre-pour-briller-sur-le-mx-des-nations-aux-usa\\\/\"},\"author\":{\"name\":\"oliviere\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#\\\/schema\\\/person\\\/11b47143d9f755babca2c9110e03235c\"},\"headline\":\"Interview &#8211; Liam Everts et les fr\u00e8res Coenen pr\u00eats \u00e0 se battre pour briller sur le MX des Nations aux USA\",\"datePublished\":\"2025-10-02T10:27:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2025\\\/10\\\/interview-liam-everts-et-les-freres-coenen-prets-a-se-battre-pour-briller-sur-le-mx-des-nations-aux-usa\\\/\"},\"wordCount\":507,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2025\\\/10\\\/interview-liam-everts-et-les-freres-coenen-prets-a-se-battre-pour-briller-sur-le-mx-des-nations-aux-usa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fr.motocrossmag.be\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/SI202508240621.avif\",\"keywords\":[\"liam everts\",\"lucas coenen\",\"Motocross\",\"motocross des nations\",\"mxdn\",\"MXGP\",\"sacha coenen\"],\"articleSection\":[\"Actualit\u00e9\",\"Interviews\",\"Interviews -all\",\"Motocross\",\"Motocross MXGP\",\"MX des Nations\",\"News\",\"News\",\"Slideshow\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2025\\\/10\\\/interview-liam-everts-et-les-freres-coenen-prets-a-se-battre-pour-briller-sur-le-mx-des-nations-aux-usa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2025\\\/10\\\/interview-liam-everts-et-les-freres-coenen-prets-a-se-battre-pour-briller-sur-le-mx-des-nations-aux-usa\\\/\",\"url\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2025\\\/10\\\/interview-liam-everts-et-les-freres-coenen-prets-a-se-battre-pour-briller-sur-le-mx-des-nations-aux-usa\\\/\",\"name\":\"Interview - Liam Everts et les fr\u00e8res Coenen pr\u00eats \u00e0 se battre pour briller sur le MX des Nations aux USA - Motocross - Enduro - Supermoto | MotocrossMag\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2025\\\/10\\\/interview-liam-everts-et-les-freres-coenen-prets-a-se-battre-pour-briller-sur-le-mx-des-nations-aux-usa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2025\\\/10\\\/interview-liam-everts-et-les-freres-coenen-prets-a-se-battre-pour-briller-sur-le-mx-des-nations-aux-usa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fr.motocrossmag.be\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/SI202508240621.avif\",\"datePublished\":\"2025-10-02T10:27:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#\\\/schema\\\/person\\\/11b47143d9f755babca2c9110e03235c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2025\\\/10\\\/interview-liam-everts-et-les-freres-coenen-prets-a-se-battre-pour-briller-sur-le-mx-des-nations-aux-usa\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2025\\\/10\\\/interview-liam-everts-et-les-freres-coenen-prets-a-se-battre-pour-briller-sur-le-mx-des-nations-aux-usa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2025\\\/10\\\/interview-liam-everts-et-les-freres-coenen-prets-a-se-battre-pour-briller-sur-le-mx-des-nations-aux-usa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fr.motocrossmag.be\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/SI202508240621.avif\",\"contentUrl\":\"https:\\\/\\\/fr.motocrossmag.be\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/SI202508240621.avif\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2025\\\/10\\\/interview-liam-everts-et-les-freres-coenen-prets-a-se-battre-pour-briller-sur-le-mx-des-nations-aux-usa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/fr.motocrossmag.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Interview &#8211; Liam Everts et les fr\u00e8res Coenen pr\u00eats \u00e0 se battre pour briller sur le MX des Nations aux USA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#website\",\"url\":\"https:\\\/\\\/fr.motocrossmag.be\\\/\",\"name\":\"Motocross - Enduro - Supermoto | MotocrossMag\",\"description\":\"L&#039;actualit\u00e9 du motocross, de l&#039;enduro et du Supermoto en ligne!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fr.motocrossmag.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#\\\/schema\\\/person\\\/11b47143d9f755babca2c9110e03235c\",\"name\":\"oliviere\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g\",\"caption\":\"oliviere\"},\"sameAs\":[\"http:\\\/\\\/www.motocrossmag.be\"],\"url\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/author\\\/oliviere\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Interview - Liam Everts et les fr\u00e8res Coenen pr\u00eats \u00e0 se battre pour briller sur le MX des Nations aux USA - Motocross - Enduro - Supermoto | MotocrossMag","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fr.motocrossmag.be\/index.php\/2025\/10\/interview-liam-everts-et-les-freres-coenen-prets-a-se-battre-pour-briller-sur-le-mx-des-nations-aux-usa\/","og_locale":"fr_FR","og_type":"article","og_title":"Interview - Liam Everts et les fr\u00e8res Coenen pr\u00eats \u00e0 se battre pour briller sur le MX des Nations aux USA - Motocross - Enduro - Supermoto | MotocrossMag","og_description":"Ce week-end, le Team Belgium sera aux \u00c9tats-Unis pour y affronter le reste du monde sur le Motocross des Nations, disput\u00e9 cette ann\u00e9e \u00e0 Crawfordsville (Indiana). Lucas Coenen, vice-champion du monde MXGP, son fr\u00e8re jumeau Sacha (MX2) et Liam Everts (Open) visent un podium face \u00e0 l\u2019\u00e9lite mondiale. Entre ambitions, bilan de saison et r\u00eaves [&hellip;]","og_url":"https:\/\/fr.motocrossmag.be\/index.php\/2025\/10\/interview-liam-everts-et-les-freres-coenen-prets-a-se-battre-pour-briller-sur-le-mx-des-nations-aux-usa\/","og_site_name":"Motocross - Enduro - Supermoto | MotocrossMag","article_published_time":"2025-10-02T10:27:23+00:00","author":"oliviere","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"oliviere","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fr.motocrossmag.be\/index.php\/2025\/10\/interview-liam-everts-et-les-freres-coenen-prets-a-se-battre-pour-briller-sur-le-mx-des-nations-aux-usa\/#article","isPartOf":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2025\/10\/interview-liam-everts-et-les-freres-coenen-prets-a-se-battre-pour-briller-sur-le-mx-des-nations-aux-usa\/"},"author":{"name":"oliviere","@id":"https:\/\/fr.motocrossmag.be\/#\/schema\/person\/11b47143d9f755babca2c9110e03235c"},"headline":"Interview &#8211; Liam Everts et les fr\u00e8res Coenen pr\u00eats \u00e0 se battre pour briller sur le MX des Nations aux USA","datePublished":"2025-10-02T10:27:23+00:00","mainEntityOfPage":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2025\/10\/interview-liam-everts-et-les-freres-coenen-prets-a-se-battre-pour-briller-sur-le-mx-des-nations-aux-usa\/"},"wordCount":507,"commentCount":0,"image":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2025\/10\/interview-liam-everts-et-les-freres-coenen-prets-a-se-battre-pour-briller-sur-le-mx-des-nations-aux-usa\/#primaryimage"},"thumbnailUrl":"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2025\/10\/SI202508240621.avif","keywords":["liam everts","lucas coenen","Motocross","motocross des nations","mxdn","MXGP","sacha coenen"],"articleSection":["Actualit\u00e9","Interviews","Interviews -all","Motocross","Motocross MXGP","MX des Nations","News","News","Slideshow"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fr.motocrossmag.be\/index.php\/2025\/10\/interview-liam-everts-et-les-freres-coenen-prets-a-se-battre-pour-briller-sur-le-mx-des-nations-aux-usa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fr.motocrossmag.be\/index.php\/2025\/10\/interview-liam-everts-et-les-freres-coenen-prets-a-se-battre-pour-briller-sur-le-mx-des-nations-aux-usa\/","url":"https:\/\/fr.motocrossmag.be\/index.php\/2025\/10\/interview-liam-everts-et-les-freres-coenen-prets-a-se-battre-pour-briller-sur-le-mx-des-nations-aux-usa\/","name":"Interview - Liam Everts et les fr\u00e8res Coenen pr\u00eats \u00e0 se battre pour briller sur le MX des Nations aux USA - Motocross - Enduro - Supermoto | MotocrossMag","isPartOf":{"@id":"https:\/\/fr.motocrossmag.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2025\/10\/interview-liam-everts-et-les-freres-coenen-prets-a-se-battre-pour-briller-sur-le-mx-des-nations-aux-usa\/#primaryimage"},"image":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2025\/10\/interview-liam-everts-et-les-freres-coenen-prets-a-se-battre-pour-briller-sur-le-mx-des-nations-aux-usa\/#primaryimage"},"thumbnailUrl":"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2025\/10\/SI202508240621.avif","datePublished":"2025-10-02T10:27:23+00:00","author":{"@id":"https:\/\/fr.motocrossmag.be\/#\/schema\/person\/11b47143d9f755babca2c9110e03235c"},"breadcrumb":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2025\/10\/interview-liam-everts-et-les-freres-coenen-prets-a-se-battre-pour-briller-sur-le-mx-des-nations-aux-usa\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fr.motocrossmag.be\/index.php\/2025\/10\/interview-liam-everts-et-les-freres-coenen-prets-a-se-battre-pour-briller-sur-le-mx-des-nations-aux-usa\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/fr.motocrossmag.be\/index.php\/2025\/10\/interview-liam-everts-et-les-freres-coenen-prets-a-se-battre-pour-briller-sur-le-mx-des-nations-aux-usa\/#primaryimage","url":"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2025\/10\/SI202508240621.avif","contentUrl":"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2025\/10\/SI202508240621.avif","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/fr.motocrossmag.be\/index.php\/2025\/10\/interview-liam-everts-et-les-freres-coenen-prets-a-se-battre-pour-briller-sur-le-mx-des-nations-aux-usa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/fr.motocrossmag.be\/"},{"@type":"ListItem","position":2,"name":"Interview &#8211; Liam Everts et les fr\u00e8res Coenen pr\u00eats \u00e0 se battre pour briller sur le MX des Nations aux USA"}]},{"@type":"WebSite","@id":"https:\/\/fr.motocrossmag.be\/#website","url":"https:\/\/fr.motocrossmag.be\/","name":"Motocross - Enduro - Supermoto | MotocrossMag","description":"L&#039;actualit\u00e9 du motocross, de l&#039;enduro et du Supermoto en ligne!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fr.motocrossmag.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/fr.motocrossmag.be\/#\/schema\/person\/11b47143d9f755babca2c9110e03235c","name":"oliviere","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g","caption":"oliviere"},"sameAs":["http:\/\/www.motocrossmag.be"],"url":"https:\/\/fr.motocrossmag.be\/index.php\/author\/oliviere\/"}]}},"_links":{"self":[{"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/posts\/151709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/users\/932"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/comments?post=151709"}],"version-history":[{"count":1,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/posts\/151709\/revisions"}],"predecessor-version":[{"id":151714,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/posts\/151709\/revisions\/151714"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/media\/151711"}],"wp:attachment":[{"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/media?parent=151709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/categories?post=151709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/tags?post=151709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}