{"id":16893,"date":"2013-01-20T17:39:36","date_gmt":"2013-01-20T16:39:36","guid":{"rendered":"http:\/\/fr.motocrossmag.be\/?p=16893"},"modified":"2013-01-21T00:43:55","modified_gmt":"2013-01-20T23:43:55","slug":"galerie-photos-les-pilotes-ktm-prennent-la-pose","status":"publish","type":"post","link":"https:\/\/fr.motocrossmag.be\/index.php\/2013\/01\/galerie-photos-les-pilotes-ktm-prennent-la-pose\/","title":{"rendered":"Galerie photos | Les pilotes KTM prennent la pose"},"content":{"rendered":"<p>Ken De Dijcker, Antonio Cairoli, Jordi Tixier et\u00a0Jeffrey Herlings prennent la pose pour le traditionnel shooting photo d&rsquo;avant-saison. D\u00e9couvrez les pilotes officiels KTM sous leurs couleurs 2013&#8230; et sous le soleil de l&rsquo;Italie et de l&rsquo;Espagne.<\/p>\n<p><a rel=\"lightbox dia=1\" href=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/70898_everts_ph_2013_jpa_09_1024.jpg\"><img decoding=\"async\" class=\"alignnone size-thumbnail wp-image-16926\" title=\"70898_everts_ph_2013_jpa_09_1024\" src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/70898_everts_ph_2013_jpa_09_1024-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>\u00a0\u00a0 <a rel=\"lightbox dia=1\" href=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/70907_herlings_ph_2013_jpa_20_1024.jpg\"><img decoding=\"async\" class=\"alignnone size-thumbnail wp-image-16925\" title=\"70907_herlings_ph_2013_jpa_20_1024\" src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/70907_herlings_ph_2013_jpa_20_1024-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>\u00a0\u00a0 <a rel=\"lightbox dia=1\" href=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/70916_tixier_ph_2013_jpa_26_1024.jpg\"><img decoding=\"async\" class=\"alignnone size-thumbnail wp-image-16924\" title=\"70916_tixier_ph_2013_jpa_26_1024\" src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/70916_tixier_ph_2013_jpa_26_1024-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><br \/>\n<a rel=\"lightbox dia=1\" href=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/70926_tixier_ph_2013_jpa_25_1024.jpg\"><img decoding=\"async\" class=\"alignnone size-thumbnail wp-image-16923\" title=\"70926_tixier_ph_2013_jpa_25_1024\" src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/70926_tixier_ph_2013_jpa_25_1024-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>\u00a0\u00a0 <a rel=\"lightbox dia=1\" href=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/70929_stefan_ecerts__72_1024.jpg\"><img decoding=\"async\" class=\"alignnone size-thumbnail wp-image-16922\" title=\"70929_stefan_ecerts__72_1024\" src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/70929_stefan_ecerts__72_1024-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>\u00a0\u00a0 <a rel=\"lightbox dia=1\" href=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/70946_mx2team_static_ph_2013_jpa_21_1024.jpg\"><img decoding=\"async\" class=\"alignnone size-thumbnail wp-image-16921\" title=\"70946_mx2team_static_ph_2013_jpa_21_1024\" src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/70946_mx2team_static_ph_2013_jpa_21_1024-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><br \/>\n<a rel=\"lightbox dia=1\" href=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/70967_069_ktm2013_cairoli_1024.jpg\"><img decoding=\"async\" class=\"alignnone size-thumbnail wp-image-16920\" title=\"70967_069_ktm2013_cairoli_1024\" src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/70967_069_ktm2013_cairoli_1024-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>\u00a0\u00a0 <a rel=\"lightbox dia=1\" href=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/70973_033_ktm2013_cairoli_1024.jpg\"><img decoding=\"async\" class=\"alignnone size-thumbnail wp-image-16919\" title=\"70973_033_ktm2013_cairoli_1024\" src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/70973_033_ktm2013_cairoli_1024-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>\u00a0\u00a0 <a rel=\"lightbox dia=1\" href=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/70976_056_ktm2013_cairoli_1024.jpg\"><img decoding=\"async\" class=\"alignnone size-thumbnail wp-image-16918\" title=\"70976_056_ktm2013_cairoli_1024\" src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/70976_056_ktm2013_cairoli_1024-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><br \/>\n<a rel=\"lightbox dia=1\" href=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/70977_058_ktm2013_cairoli_1024.jpg\"><img decoding=\"async\" class=\"alignnone size-thumbnail wp-image-16917\" title=\"70977_058_ktm2013_cairoli_1024\" src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/70977_058_ktm2013_cairoli_1024-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>\u00a0\u00a0 <a rel=\"lightbox dia=1\" href=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/70980_068_ktm2013_cairoli_1024.jpg\"><img decoding=\"async\" class=\"alignnone size-thumbnail wp-image-16916\" title=\"70980_068_ktm2013_cairoli_1024\" src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/70980_068_ktm2013_cairoli_1024-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>\u00a0\u00a0 <a rel=\"lightbox dia=1\" href=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/70981_074_ktm2013_dedycker_1024.jpg\"><img decoding=\"async\" class=\"alignnone size-thumbnail wp-image-16915\" title=\"70981_074_ktm2013_dedycker_1024\" src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/70981_074_ktm2013_dedycker_1024-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><br \/>\n<a rel=\"lightbox dia=1\" href=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/70986_020_ktm2013_dedycker_1024.jpg\"><img decoding=\"async\" class=\"alignnone size-thumbnail wp-image-16914\" title=\"70986_020_ktm2013_dedycker_1024\" src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/70986_020_ktm2013_dedycker_1024-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>\u00a0\u00a0 <a rel=\"lightbox dia=1\" href=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/70987_022_ktm2013_dedycker_1024.jpg\"><img decoding=\"async\" class=\"alignnone size-thumbnail wp-image-16913\" title=\"70987_022_ktm2013_dedycker_1024\" src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/70987_022_ktm2013_dedycker_1024-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>\u00a0\u00a0 <a rel=\"lightbox dia=1\" href=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/70992_052_ktm2013_dedycker_1024.jpg\"><img decoding=\"async\" class=\"alignnone size-thumbnail wp-image-16912\" title=\"70992_052_ktm2013_dedycker_1024\" src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/70992_052_ktm2013_dedycker_1024-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><br \/>\n<a rel=\"lightbox dia=1\" href=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/70995_016_ktm2013_cairoli_dedycker_1024.jpg\"><img decoding=\"async\" class=\"alignnone size-thumbnail wp-image-16911\" title=\"70995_016_ktm2013_cairoli_dedycker_1024\" src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/70995_016_ktm2013_cairoli_dedycker_1024-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>\u00a0\u00a0 <a rel=\"lightbox dia=1\" href=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/70997_008_ktm2013_cairoli_dedycker_1024.jpg\"><img decoding=\"async\" class=\"alignnone size-thumbnail wp-image-16910\" title=\"70997_008_ktm2013_cairoli_dedycker_1024\" src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/70997_008_ktm2013_cairoli_dedycker_1024-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>\u00a0\u00a0 <a rel=\"lightbox dia=1\" href=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/70998_011_ktm2013_cairoli_dedycker_1024.jpg\"><img decoding=\"async\" class=\"alignnone size-thumbnail wp-image-16909\" title=\"70998_011_ktm2013_cairoli_dedycker_1024\" src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/70998_011_ktm2013_cairoli_dedycker_1024-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><br \/>\n<a rel=\"lightbox dia=1\" href=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/71008_037_ktm2013_cairoli_1024.jpg\"><img decoding=\"async\" class=\"alignnone size-thumbnail wp-image-16908\" title=\"71008_037_ktm2013_cairoli_1024\" src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/71008_037_ktm2013_cairoli_1024-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>\u00a0\u00a0 <a rel=\"lightbox dia=1\" href=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/71019_067_ktm2013_dedycker_1024.jpg\"><img decoding=\"async\" class=\"alignnone size-thumbnail wp-image-16907\" title=\"71019_067_ktm2013_dedycker_1024\" src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/71019_067_ktm2013_dedycker_1024-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>\u00a0\u00a0 <a rel=\"lightbox dia=1\" href=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/71026_017_ktm2013_dedycker_cairoli_decarli_1024.jpg\"><img decoding=\"async\" class=\"alignnone size-thumbnail wp-image-16906\" title=\"71026_017_ktm2013_dedycker_cairoli_decarli_1024\" src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/71026_017_ktm2013_dedycker_cairoli_decarli_1024-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/p><div class=\"qtkmc6a97b316daf57\" ><!-- \/91277017\/Inline-articles-mobile -->\n<div style=\"margin:auto; text-align:center !important\">\n<div id='div-gpt-ad-1784982661365-0' style='min-width: 250px; min-height: 75px;'>\n  <script>\n    googletag.cmd.push(function() { googletag.display('div-gpt-ad-1784982661365-0'); });\n  <\/script>\n<\/div><\/div><\/div><style type=\"text\/css\">\r\n.qtkmc6a97b316daf57 {\r\nmargin-bottom:30px;margin-top:20px\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.qtkmc6a97b316daf57 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.qtkmc6a97b316daf57 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.qtkmc6a97b316daf57 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.qtkmc6a97b316daf57 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.qtkmc6a97b316daf57 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n\n","protected":false},"excerpt":{"rendered":"<p>Ken De Dijcker, Antonio Cairoli, Jordi Tixier et\u00a0Jeffrey Herlings prennent la pose pour le traditionnel shooting photo d&rsquo;avant-saison. D\u00e9couvrez les pilotes officiels KTM sous leurs couleurs 2013&#8230; et sous le soleil de l&rsquo;Italie et de l&rsquo;Espagne. \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0<\/p>\n","protected":false},"author":932,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[66,65],"tags":[],"class_list":["post-16893","post","type-post","status-publish","format-standard","category-photos","category-slideshow"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Galerie photos | Les pilotes KTM prennent la pose - Motocross - Enduro - Supermoto | MotocrossMag<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fr.motocrossmag.be\/index.php\/2013\/01\/galerie-photos-les-pilotes-ktm-prennent-la-pose\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Galerie photos | Les pilotes KTM prennent la pose - Motocross - Enduro - Supermoto | MotocrossMag\" \/>\n<meta property=\"og:description\" content=\"Ken De Dijcker, Antonio Cairoli, Jordi Tixier et\u00a0Jeffrey Herlings prennent la pose pour le traditionnel shooting photo d&rsquo;avant-saison. D\u00e9couvrez les pilotes officiels KTM sous leurs couleurs 2013&#8230; et sous le soleil de l&rsquo;Italie et de l&rsquo;Espagne. \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fr.motocrossmag.be\/index.php\/2013\/01\/galerie-photos-les-pilotes-ktm-prennent-la-pose\/\" \/>\n<meta property=\"og:site_name\" content=\"Motocross - Enduro - Supermoto | MotocrossMag\" \/>\n<meta property=\"article:published_time\" content=\"2013-01-20T16:39:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-01-20T23:43:55+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/70898_everts_ph_2013_jpa_09_1024-150x150.jpg\" \/>\n<meta name=\"author\" content=\"oliviere\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"oliviere\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2013\\\/01\\\/galerie-photos-les-pilotes-ktm-prennent-la-pose\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2013\\\/01\\\/galerie-photos-les-pilotes-ktm-prennent-la-pose\\\/\"},\"author\":{\"name\":\"oliviere\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#\\\/schema\\\/person\\\/11b47143d9f755babca2c9110e03235c\"},\"headline\":\"Galerie photos | Les pilotes KTM prennent la pose\",\"datePublished\":\"2013-01-20T16:39:36+00:00\",\"dateModified\":\"2013-01-20T23:43:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2013\\\/01\\\/galerie-photos-les-pilotes-ktm-prennent-la-pose\\\/\"},\"wordCount\":48,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2013\\\/01\\\/galerie-photos-les-pilotes-ktm-prennent-la-pose\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/fr.motocrossmag.be\\\/wp-content\\\/uploads\\\/2013\\\/01\\\/70898_everts_ph_2013_jpa_09_1024-150x150.jpg\",\"articleSection\":[\"Photos\",\"Slideshow\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2013\\\/01\\\/galerie-photos-les-pilotes-ktm-prennent-la-pose\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2013\\\/01\\\/galerie-photos-les-pilotes-ktm-prennent-la-pose\\\/\",\"url\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2013\\\/01\\\/galerie-photos-les-pilotes-ktm-prennent-la-pose\\\/\",\"name\":\"Galerie photos | Les pilotes KTM prennent la pose - Motocross - Enduro - Supermoto | MotocrossMag\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2013\\\/01\\\/galerie-photos-les-pilotes-ktm-prennent-la-pose\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2013\\\/01\\\/galerie-photos-les-pilotes-ktm-prennent-la-pose\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/fr.motocrossmag.be\\\/wp-content\\\/uploads\\\/2013\\\/01\\\/70898_everts_ph_2013_jpa_09_1024-150x150.jpg\",\"datePublished\":\"2013-01-20T16:39:36+00:00\",\"dateModified\":\"2013-01-20T23:43:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#\\\/schema\\\/person\\\/11b47143d9f755babca2c9110e03235c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2013\\\/01\\\/galerie-photos-les-pilotes-ktm-prennent-la-pose\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2013\\\/01\\\/galerie-photos-les-pilotes-ktm-prennent-la-pose\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2013\\\/01\\\/galerie-photos-les-pilotes-ktm-prennent-la-pose\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fr.motocrossmag.be\\\/wp-content\\\/uploads\\\/2013\\\/01\\\/70898_everts_ph_2013_jpa_09_1024.jpg\",\"contentUrl\":\"https:\\\/\\\/fr.motocrossmag.be\\\/wp-content\\\/uploads\\\/2013\\\/01\\\/70898_everts_ph_2013_jpa_09_1024.jpg\",\"width\":900,\"height\":599},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2013\\\/01\\\/galerie-photos-les-pilotes-ktm-prennent-la-pose\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/fr.motocrossmag.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Galerie photos | Les pilotes KTM prennent la pose\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#website\",\"url\":\"https:\\\/\\\/fr.motocrossmag.be\\\/\",\"name\":\"Motocross - Enduro - Supermoto | MotocrossMag\",\"description\":\"L&#039;actualit\u00e9 du motocross, de l&#039;enduro et du Supermoto en ligne!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fr.motocrossmag.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#\\\/schema\\\/person\\\/11b47143d9f755babca2c9110e03235c\",\"name\":\"oliviere\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g\",\"caption\":\"oliviere\"},\"sameAs\":[\"http:\\\/\\\/www.motocrossmag.be\"],\"url\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/author\\\/oliviere\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Galerie photos | Les pilotes KTM prennent la pose - Motocross - Enduro - Supermoto | MotocrossMag","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fr.motocrossmag.be\/index.php\/2013\/01\/galerie-photos-les-pilotes-ktm-prennent-la-pose\/","og_locale":"fr_FR","og_type":"article","og_title":"Galerie photos | Les pilotes KTM prennent la pose - Motocross - Enduro - Supermoto | MotocrossMag","og_description":"Ken De Dijcker, Antonio Cairoli, Jordi Tixier et\u00a0Jeffrey Herlings prennent la pose pour le traditionnel shooting photo d&rsquo;avant-saison. D\u00e9couvrez les pilotes officiels KTM sous leurs couleurs 2013&#8230; et sous le soleil de l&rsquo;Italie et de l&rsquo;Espagne. \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0","og_url":"https:\/\/fr.motocrossmag.be\/index.php\/2013\/01\/galerie-photos-les-pilotes-ktm-prennent-la-pose\/","og_site_name":"Motocross - Enduro - Supermoto | MotocrossMag","article_published_time":"2013-01-20T16:39:36+00:00","article_modified_time":"2013-01-20T23:43:55+00:00","og_image":[{"url":"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/70898_everts_ph_2013_jpa_09_1024-150x150.jpg","type":"","width":"","height":""}],"author":"oliviere","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"oliviere"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fr.motocrossmag.be\/index.php\/2013\/01\/galerie-photos-les-pilotes-ktm-prennent-la-pose\/#article","isPartOf":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2013\/01\/galerie-photos-les-pilotes-ktm-prennent-la-pose\/"},"author":{"name":"oliviere","@id":"https:\/\/fr.motocrossmag.be\/#\/schema\/person\/11b47143d9f755babca2c9110e03235c"},"headline":"Galerie photos | Les pilotes KTM prennent la pose","datePublished":"2013-01-20T16:39:36+00:00","dateModified":"2013-01-20T23:43:55+00:00","mainEntityOfPage":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2013\/01\/galerie-photos-les-pilotes-ktm-prennent-la-pose\/"},"wordCount":48,"commentCount":0,"image":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2013\/01\/galerie-photos-les-pilotes-ktm-prennent-la-pose\/#primaryimage"},"thumbnailUrl":"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/70898_everts_ph_2013_jpa_09_1024-150x150.jpg","articleSection":["Photos","Slideshow"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fr.motocrossmag.be\/index.php\/2013\/01\/galerie-photos-les-pilotes-ktm-prennent-la-pose\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fr.motocrossmag.be\/index.php\/2013\/01\/galerie-photos-les-pilotes-ktm-prennent-la-pose\/","url":"https:\/\/fr.motocrossmag.be\/index.php\/2013\/01\/galerie-photos-les-pilotes-ktm-prennent-la-pose\/","name":"Galerie photos | Les pilotes KTM prennent la pose - Motocross - Enduro - Supermoto | MotocrossMag","isPartOf":{"@id":"https:\/\/fr.motocrossmag.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2013\/01\/galerie-photos-les-pilotes-ktm-prennent-la-pose\/#primaryimage"},"image":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2013\/01\/galerie-photos-les-pilotes-ktm-prennent-la-pose\/#primaryimage"},"thumbnailUrl":"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/70898_everts_ph_2013_jpa_09_1024-150x150.jpg","datePublished":"2013-01-20T16:39:36+00:00","dateModified":"2013-01-20T23:43:55+00:00","author":{"@id":"https:\/\/fr.motocrossmag.be\/#\/schema\/person\/11b47143d9f755babca2c9110e03235c"},"breadcrumb":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2013\/01\/galerie-photos-les-pilotes-ktm-prennent-la-pose\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fr.motocrossmag.be\/index.php\/2013\/01\/galerie-photos-les-pilotes-ktm-prennent-la-pose\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/fr.motocrossmag.be\/index.php\/2013\/01\/galerie-photos-les-pilotes-ktm-prennent-la-pose\/#primaryimage","url":"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/70898_everts_ph_2013_jpa_09_1024.jpg","contentUrl":"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/01\/70898_everts_ph_2013_jpa_09_1024.jpg","width":900,"height":599},{"@type":"BreadcrumbList","@id":"https:\/\/fr.motocrossmag.be\/index.php\/2013\/01\/galerie-photos-les-pilotes-ktm-prennent-la-pose\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/fr.motocrossmag.be\/"},{"@type":"ListItem","position":2,"name":"Galerie photos | Les pilotes KTM prennent la pose"}]},{"@type":"WebSite","@id":"https:\/\/fr.motocrossmag.be\/#website","url":"https:\/\/fr.motocrossmag.be\/","name":"Motocross - Enduro - Supermoto | MotocrossMag","description":"L&#039;actualit\u00e9 du motocross, de l&#039;enduro et du Supermoto en ligne!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fr.motocrossmag.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/fr.motocrossmag.be\/#\/schema\/person\/11b47143d9f755babca2c9110e03235c","name":"oliviere","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g","caption":"oliviere"},"sameAs":["http:\/\/www.motocrossmag.be"],"url":"https:\/\/fr.motocrossmag.be\/index.php\/author\/oliviere\/"}]}},"_links":{"self":[{"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/posts\/16893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/users\/932"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/comments?post=16893"}],"version-history":[{"count":0,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/posts\/16893\/revisions"}],"wp:attachment":[{"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/media?parent=16893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/categories?post=16893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/tags?post=16893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}