{"id":18296,"date":"2013-06-27T23:06:18","date_gmt":"2013-06-27T22:06:18","guid":{"rendered":"http:\/\/fr.motocrossmag.be\/?p=18296"},"modified":"2013-06-27T23:06:18","modified_gmt":"2013-06-27T22:06:18","slug":"motocross-fmb-lommel","status":"publish","type":"post","link":"https:\/\/fr.motocrossmag.be\/index.php\/2013\/06\/motocross-fmb-lommel\/","title":{"rendered":"Motocross FMB &#8211; Lommel  | Championnats de Belgique et de Wallonie ce week-end dans le sable de Lommel"},"content":{"rendered":"<p>La deuxi\u00e8me organisation de la saison de l&rsquo;AMC Evergem se d\u00e9roulera ce week-end \u00e0\u00a0 Lommel. Les\u00a0pilotes FMB pourront y marquer des points pour le championnat de Belgique. Les quads sont \u00e9galement pr\u00e9vus au programme cette ann\u00e9e tandis qu&rsquo;on roulera le samedi dans le cadre du championnat de Wallonie FMWB\/FPCNA. Un programme bien rempli!<\/p>\n<p>D\u00e8s 8h00 le samedi,\u00a0les pilotes FPCNA\u00a0entammeront leur programme. Les pilotes FMB, \u00e0\u00a0 l&rsquo;exception des Inters et des Nationaux, pourront participer aux courses FPCNA et profiter ainis d&rsquo;un excellent entra\u00eenement pour le lendemain. Une course pour les pilotes \u00ab\u00a0Loisirs\u00a0\u00bb est \u00e9galement pr\u00e9vue.<\/p>\n<p><strong>Marvin Vandaele en leader dans la Challenger Cup<\/strong><\/p>\n<p>Le dimanche, ce sera au tour\u00a0de cat\u00e9gories FMB de prendre possession de la piste de Lommel. Tous les pilotes pourront marquer des points pour le championnat de Belgque et les sp\u00e9cialistes du sable devront\u00a0se mettre en \u00e9vidence\u00a0car Balen sera apr\u00e8s Lommel le seul circuit de sable \u00e0\u00a0 rester au programme de la FMB.<\/p>\n<p>Dans le Challenger Cup, on suivra avec int\u00e9r\u00eat le comportement du leader du championnat Marvin Vandaele face aux Honda de Kristof Salaets et de\u00a0Nick Triest, ses plus s\u00e9rieux rivaux dans la course au titre avec Jeffrey Dewulf \u00e0\u00a0 pr\u00e9sent sur une 450 et souvent tr\u00e8s rapide dans le sable. D&rsquo;autres noms \u00e0\u00a0 retenir: J\u00e9r\u00e9my Delinc\u00e9, Gunther Ghysels, Mark Boot, Adrien Van Beveren et Marc Dereuver.<\/p>\n<p><strong>En pratique<\/strong><\/p>\n<p>Le parc des coureurs est s\u00e9par\u00e9 afin d&rsquo;\u00e9viter les probl\u00e8mes de trafic. Il sera ouvert \u00e0\u00a0 partir du vendredi \u00e0\u00a0 17h00 et l&rsquo;entr\u00e9e pour les deux jours est de seulement 12 EUR.\u00a0<br \/>\nLes inscriptions pour les licenci\u00e9s FMB et FPCNA comme pour les licenci\u00e9s \u00e0\u00a0 la journ\u00e9e se feront dans la cantine.<\/p>\n<p><strong><span style=\"color: #800000;\">Classements provisoires<\/span><\/strong><\/p>\n<p>85 cc<\/p>\n<p>1. Thomas van Erum 275<br \/>\n2. Benjamin Doneux 208<br \/>\n3. Remi Fraikin 196<br \/>\n4. Jens Bogaerts 187<br \/>\n5. Ian De Sweemer 139<\/p>\n<p>Espoirs MX2<\/p>\n<p>1. Karel Schepmans 265<br \/>\n2. Zinno Bonnez 253<br \/>\n3. Keani Clement 173<br \/>\n4. Maiky Dubie 139<br \/>\n5. Yannick Vertommen 129<\/p>\n<p>Espoirs 2-temps<\/p>\n<p>1. Dorian Deville 246<br \/>\n2. Brian Engelen 227<br \/>\n3. Michiel Breugelmans 207<br \/>\n4. Yente Dourte 205<br \/>\n5. Jordi Van Mieghem 197<\/p>\n<p>Seniors<\/p>\n<p>1. Hans Alenteyns 234<br \/>\n2. Niels Haccuria 205<br \/>\n3. Andy Alenteyns 202<br \/>\n4. Niki Margetic 173<br \/>\n5. Moreno Lubkemann 157<\/p>\n<p>Juniors MX2<\/p>\n<p>1. Robin Gilissen 203<br \/>\n2. Kevin Demey 191<br \/>\n3. Ken Craeghs 176<br \/>\n4. Joshua Feytons 173<br \/>\n5. Mathieu Aerts 159<\/p>\n<p>Juniors MX1<\/p>\n<p>1. Joery Schroeders 224<br \/>\n2. Bruno Colmant 217<br \/>\n3. Melvin Calrinval 193<br \/>\n4. Randy Vandecasteele 172<br \/>\n5. Jaimy Vandamme 164<\/p>\n<p>Masters<\/p>\n<p>1. Dirk Paridaens 208<br \/>\n2. Patrick Schurmans 174<br \/>\n3. Roland Guilmin 147<br \/>\n4. Eric Siriez 144<br \/>\n5. Daniel Droesch 137<\/p>\n<p>Nationaux MX2<\/p>\n<p>1. Olvier Vandergugten 187<br \/>\n2. Axel Nijs 182<br \/>\n3. Heikki Geens 182<br \/>\n4. Kevin Van Geldorp 179<br \/>\n5. Jeroen Nijs 101<\/p>\n<p>Nationaux MX1<\/p>\n<p>1. Joni Coemans 186<br \/>\n2. Jochen Walckiers 157<br \/>\n3. Jerry Nuydens 151<br \/>\n4. Donny Schmidt 149<br \/>\n5. Tom Schepmans 142<\/p>\n<p>Quads<\/p>\n<p>1. Davy De Cuyper 134<br \/>\n2. Sunny Desintubin 118<br \/>\n3. Olivier Vandendijck 88<br \/>\n4. Peter Steegmans 75<br \/>\n5. Jan Vlaeymans 67<\/p>\n<p>Inters<\/p>\n<p>1. Marvin Vandaele 184<br \/>\n2. Kristof Salaets 138<br \/>\n3. Nick Triest 133<br \/>\n4. Jeffrey Dewulf 86<br \/>\n5. Andy Truyts 68<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La deuxi\u00e8me organisation de la saison de l&rsquo;AMC Evergem se d\u00e9roulera ce week-end \u00e0\u00a0 Lommel. Les\u00a0pilotes FMB pourront y marquer des points pour le championnat de Belgique. Les quads sont [&#8230;]<\/p>\n","protected":false},"author":932,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,29,1,65],"tags":[],"class_list":["post-18296","post","type-post","status-publish","format-standard","hentry","category-motocross","category-fmb","category-non-classe","category-slideshow"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Motocross FMB - Lommel | Championnats de Belgique et de Wallonie ce week-end dans le sable de Lommel - Motocross - Enduro - Supermoto | MotocrossMag<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fr.motocrossmag.be\/index.php\/2013\/06\/motocross-fmb-lommel\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Motocross FMB - Lommel | Championnats de Belgique et de Wallonie ce week-end dans le sable de Lommel - Motocross - Enduro - Supermoto | MotocrossMag\" \/>\n<meta property=\"og:description\" content=\"La deuxi\u00e8me organisation de la saison de l&rsquo;AMC Evergem se d\u00e9roulera ce week-end \u00e0\u00a0 Lommel. Les\u00a0pilotes FMB pourront y marquer des points pour le championnat de Belgique. Les quads sont [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fr.motocrossmag.be\/index.php\/2013\/06\/motocross-fmb-lommel\/\" \/>\n<meta property=\"og:site_name\" content=\"Motocross - Enduro - Supermoto | MotocrossMag\" \/>\n<meta property=\"article:published_time\" content=\"2013-06-27T22:06:18+00:00\" \/>\n<meta name=\"author\" content=\"oliviere\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"oliviere\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2013\\\/06\\\/motocross-fmb-lommel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2013\\\/06\\\/motocross-fmb-lommel\\\/\"},\"author\":{\"name\":\"oliviere\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#\\\/schema\\\/person\\\/11b47143d9f755babca2c9110e03235c\"},\"headline\":\"Motocross FMB &#8211; Lommel | Championnats de Belgique et de Wallonie ce week-end dans le sable de Lommel\",\"datePublished\":\"2013-06-27T22:06:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2013\\\/06\\\/motocross-fmb-lommel\\\/\"},\"wordCount\":453,\"commentCount\":0,\"articleSection\":{\"0\":\"Motocross\",\"1\":\"Motocross FMB\",\"3\":\"Slideshow\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2013\\\/06\\\/motocross-fmb-lommel\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2013\\\/06\\\/motocross-fmb-lommel\\\/\",\"url\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2013\\\/06\\\/motocross-fmb-lommel\\\/\",\"name\":\"Motocross FMB - Lommel | Championnats de Belgique et de Wallonie ce week-end dans le sable de Lommel - Motocross - Enduro - Supermoto | MotocrossMag\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#website\"},\"datePublished\":\"2013-06-27T22:06:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#\\\/schema\\\/person\\\/11b47143d9f755babca2c9110e03235c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2013\\\/06\\\/motocross-fmb-lommel\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2013\\\/06\\\/motocross-fmb-lommel\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2013\\\/06\\\/motocross-fmb-lommel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/fr.motocrossmag.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Motocross FMB &#8211; Lommel | Championnats de Belgique et de Wallonie ce week-end dans le sable de Lommel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#website\",\"url\":\"https:\\\/\\\/fr.motocrossmag.be\\\/\",\"name\":\"Motocross - Enduro - Supermoto | MotocrossMag\",\"description\":\"L&#039;actualit\u00e9 du motocross, de l&#039;enduro et du Supermoto en ligne!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fr.motocrossmag.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#\\\/schema\\\/person\\\/11b47143d9f755babca2c9110e03235c\",\"name\":\"oliviere\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g\",\"caption\":\"oliviere\"},\"sameAs\":[\"http:\\\/\\\/www.motocrossmag.be\"],\"url\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/author\\\/oliviere\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Motocross FMB - Lommel | Championnats de Belgique et de Wallonie ce week-end dans le sable de Lommel - Motocross - Enduro - Supermoto | MotocrossMag","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fr.motocrossmag.be\/index.php\/2013\/06\/motocross-fmb-lommel\/","og_locale":"fr_FR","og_type":"article","og_title":"Motocross FMB - Lommel | Championnats de Belgique et de Wallonie ce week-end dans le sable de Lommel - Motocross - Enduro - Supermoto | MotocrossMag","og_description":"La deuxi\u00e8me organisation de la saison de l&rsquo;AMC Evergem se d\u00e9roulera ce week-end \u00e0\u00a0 Lommel. Les\u00a0pilotes FMB pourront y marquer des points pour le championnat de Belgique. Les quads sont [...]","og_url":"https:\/\/fr.motocrossmag.be\/index.php\/2013\/06\/motocross-fmb-lommel\/","og_site_name":"Motocross - Enduro - Supermoto | MotocrossMag","article_published_time":"2013-06-27T22:06:18+00:00","author":"oliviere","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"oliviere","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fr.motocrossmag.be\/index.php\/2013\/06\/motocross-fmb-lommel\/#article","isPartOf":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2013\/06\/motocross-fmb-lommel\/"},"author":{"name":"oliviere","@id":"https:\/\/fr.motocrossmag.be\/#\/schema\/person\/11b47143d9f755babca2c9110e03235c"},"headline":"Motocross FMB &#8211; Lommel | Championnats de Belgique et de Wallonie ce week-end dans le sable de Lommel","datePublished":"2013-06-27T22:06:18+00:00","mainEntityOfPage":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2013\/06\/motocross-fmb-lommel\/"},"wordCount":453,"commentCount":0,"articleSection":{"0":"Motocross","1":"Motocross FMB","3":"Slideshow"},"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fr.motocrossmag.be\/index.php\/2013\/06\/motocross-fmb-lommel\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fr.motocrossmag.be\/index.php\/2013\/06\/motocross-fmb-lommel\/","url":"https:\/\/fr.motocrossmag.be\/index.php\/2013\/06\/motocross-fmb-lommel\/","name":"Motocross FMB - Lommel | Championnats de Belgique et de Wallonie ce week-end dans le sable de Lommel - Motocross - Enduro - Supermoto | MotocrossMag","isPartOf":{"@id":"https:\/\/fr.motocrossmag.be\/#website"},"datePublished":"2013-06-27T22:06:18+00:00","author":{"@id":"https:\/\/fr.motocrossmag.be\/#\/schema\/person\/11b47143d9f755babca2c9110e03235c"},"breadcrumb":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2013\/06\/motocross-fmb-lommel\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fr.motocrossmag.be\/index.php\/2013\/06\/motocross-fmb-lommel\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fr.motocrossmag.be\/index.php\/2013\/06\/motocross-fmb-lommel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/fr.motocrossmag.be\/"},{"@type":"ListItem","position":2,"name":"Motocross FMB &#8211; Lommel | Championnats de Belgique et de Wallonie ce week-end dans le sable de Lommel"}]},{"@type":"WebSite","@id":"https:\/\/fr.motocrossmag.be\/#website","url":"https:\/\/fr.motocrossmag.be\/","name":"Motocross - Enduro - Supermoto | MotocrossMag","description":"L&#039;actualit\u00e9 du motocross, de l&#039;enduro et du Supermoto en ligne!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fr.motocrossmag.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/fr.motocrossmag.be\/#\/schema\/person\/11b47143d9f755babca2c9110e03235c","name":"oliviere","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g","caption":"oliviere"},"sameAs":["http:\/\/www.motocrossmag.be"],"url":"https:\/\/fr.motocrossmag.be\/index.php\/author\/oliviere\/"}]}},"_links":{"self":[{"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/posts\/18296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/users\/932"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/comments?post=18296"}],"version-history":[{"count":0,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/posts\/18296\/revisions"}],"wp:attachment":[{"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/media?parent=18296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/categories?post=18296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/tags?post=18296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}