{"id":19514,"date":"2013-09-30T16:02:56","date_gmt":"2013-09-30T15:02:56","guid":{"rendered":"http:\/\/fr.motocrossmag.be\/?p=19514"},"modified":"2013-09-30T23:02:05","modified_gmt":"2013-09-30T22:02:05","slug":"motocross-des-nations-teutschenthal-les-reactions-des-pilotes","status":"publish","type":"post","link":"https:\/\/fr.motocrossmag.be\/index.php\/2013\/09\/motocross-des-nations-teutschenthal-les-reactions-des-pilotes\/","title":{"rendered":"Motocross des Nations &#8211; Teutschenthal | Les r\u00e9actions des pilotes"},"content":{"rendered":"<p><a href=\"Aucune\"><\/a>Le motocross reste un sport extr\u00eamement populaire comme on a pu encore le constater ce week-end \u00e0\u00a0 Teutschenthal, en Allemagne. En effet, m\u00eame s&rsquo;il faut se m\u00e9fier des estimations &#8211; 85.000 spectateurs durant le week-end selon les organisateurs &#8211; c&rsquo;est une \u00e9vidence que la foule \u00e9tait \u00e9norme qui ceinturait au plus pr\u00e8s un circuit \u00e0\u00a0 l&rsquo;ancienne. Et quelle ferveur! Tout cela dans une ambiance bon enfant qui montrait que chaque supporter \u00e9tait heureux de communier \u00e0\u00a0 cette grand&rsquo; messe du motocross quelles que soient les chances de son pays de figurer sur le podium.<\/p>\n<p><img decoding=\"async\" class=\"lazyload alignnone size-full wp-image-19522\" title=\"La grande foule \u00e0\u00a0 Teutschenthal\" src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/09\/la-foule.jpg\" data-orig-src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/09\/la-foule.jpg\" alt=\"\" width=\"500\" height=\"333\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27500%27%20height%3D%27333%27%20viewBox%3D%270%200%20500%20333%27%3E%3Crect%20width%3D%27500%27%20height%3D%27333%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/09\/la-foule-300x199.jpg 300w, https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/09\/la-foule.jpg 500w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>Question suspens, nous les Belges avons \u00e9t\u00e9 servis puisque la derni\u00e8re manche a vu Cl\u00e9ment Desalle \u00eatre oblig\u00e9 d&rsquo;abandonner suite \u00e0\u00a0 une chute dans le premier virage. Heureusement pour les &lsquo;Belgian Knights&rsquo;, Justin Barcia avait \u00e9t\u00e9 pris dans la m\u00eame chute que Desalle et m\u00eame s&rsquo;il repartait, l&rsquo;Am\u00e9ricain \u00e9tait tr\u00e8s attard\u00e9. L&rsquo;occasion pour notre Keeno national de montrer \u00e0\u00a0 tous qu&rsquo;il avait la carrure d&rsquo;un h\u00e9ros. Oubliant sa performance moyenne de la premi\u00e8re manche, se trouvant septi\u00e8me au d\u00e9part et simplement mis au courant qu&rsquo;il devait accumuler un maximum de points, De Dijcker se mit \u00e0\u00a0 remonter un apr\u00e8s l&rsquo;autre les pilotes qui le pr\u00e9c\u00e9daient pour terminer second \u00e0\u00a0 deux secondes du vainqueur, l&rsquo;imbattable Antonio Cairoli. Si chacun &#8211; nous pensons \u00e0\u00a0 van Horebeek revenu de la trente-quatri\u00e8me place \u00e0\u00a0 la septi\u00e8me en premi\u00e8re manche et \u00e0\u00a0 la troisi\u00e8me place de Cl\u00e9m\u00e9nt Desalle dans la seconde manche -a apport\u00e9 sa pierre \u00e0\u00a0 l&rsquo;\u00e9difice, l&rsquo;exploit de De Dijcker restera dans les m\u00e9moires de ceux qui ont assist\u00e9 \u00e0\u00a0 cette course qui a permis aux Belges de monter sur la premi\u00e8re marche du podium apr\u00e8s\u00a0dix ans d&rsquo;abstinence.<\/p>\n<p><strong><span style=\"color: #800000;\">R\u00e9actions<\/span><\/strong><\/p>\n<p><strong>Jo\u00ebl Smets<\/strong> (Manager Team Belgique): \u00e2\u20ac\u02dcC&rsquo;est la course la plus folle \u00e0\u00a0 laquelle j&rsquo;aie jamais particip\u00e9!Lors du d\u00e9part de la derni\u00e8re manche, lorsque j&rsquo;ai vu Cl\u00e9ment au sol, j&rsquo;ai pens\u00e9 que toues nos&rsquo;\u00eatre pr\u00e9sent \u00e0\u00a0 cette grand chances de l&#8217;emporter venaient de s&rsquo;envoler. Je me suis alors dirig\u00e9 directement vers le premier poste de secours pour qu&rsquo;on vienne en aide \u00e0\u00a0 Cl\u00e9ment mais je ne pensais certainement plus \u00e0\u00a0 la victoire. Lorsque j&rsquo;ai entendu au bout d&rsquo;une demi-heure que nous \u00e9tions toujours en t\u00eate, je n&rsquo;en croyais pas mes oreilles. Les derniers tours ont \u00e9t\u00e9 fantastiques. Je remercie mes pilotes pour ce qu&rsquo;ils ont r\u00e9alis\u00e9. Je suis le plus heureux des hommes!\u00a0\u00bb<\/p>\n<p><img decoding=\"async\" class=\"lazyload alignnone size-full wp-image-19520\" title=\"Jo\u00ebl Smets: heureux!\" src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/09\/smets.jpg\" data-orig-src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/09\/smets.jpg\" alt=\"\" width=\"500\" height=\"333\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27500%27%20height%3D%27333%27%20viewBox%3D%270%200%20500%20333%27%3E%3Crect%20width%3D%27500%27%20height%3D%27333%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/09\/smets-300x199.jpg 300w, https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/09\/smets.jpg 500w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n<p><strong>Jeremy van Horebeek<\/strong> (Belgique : 1er &#8211; MX2: 7-7): \u00e2\u20ac\u02dcLors de la premi\u00e8re manche, j&rsquo;\u00e9tais tr\u00e8s nerveux mais la course s&rsquo;est bien d\u00e9roul\u00e9e. Dans la deuxi\u00e8me manche, je suis tomb\u00e9 et j&rsquo;ai pens\u00e9 que c&rsquo;\u00e9tait fini. Quoiqu&rsquo;il en soit, je suis reparti le couteau entre les dents et j&rsquo;ai donn\u00e9 tout ce que j&rsquo;avais. C&rsquo;est ainsi que j&rsquo;ai pu remonter de la trente-quatri\u00e8me \u00e0\u00a0 la septi\u00e8me place. J&rsquo;\u00e9tais vraiment content de moi. C&rsquo;\u00e9tait vraiment un d\u00e9fi de remonter sur une 250. Lorsque Cl\u00e9ment est tomb\u00e9 dans la derni\u00e8re manche, toutes nos chances de victoire \u00e9taient dans les mains de Ken et j&rsquo;ai regarder la man,che en \u00e9tant \u00e9videmment tr\u00e8s nerveux. Remporter les Nations, c&rsquo;\u00e9tait un r\u00eave d&rsquo;enfant et je veux remercier tous ceux qui sont impliqu\u00e9s de loin ou de pr\u00e8s dans cette victoire.\u00a0\u00bb<\/p>\n<p><img decoding=\"async\" class=\"lazyload alignnone size-full wp-image-19519\" title=\"Jeremy Van Horebeek a cl\u00f4tur\u00e9 brillament sa saison 2013\" src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/09\/jeremy-van-horebeek.jpg\" data-orig-src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/09\/jeremy-van-horebeek.jpg\" alt=\"\" width=\"500\" height=\"332\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27500%27%20height%3D%27332%27%20viewBox%3D%270%200%20500%20332%27%3E%3Crect%20width%3D%27500%27%20height%3D%27332%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/09\/jeremy-van-horebeek-300x199.jpg 300w, https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/09\/jeremy-van-horebeek.jpg 500w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n<p><strong>Ken De Dycker<\/strong> (Belgique : 1er &#8211; MX1: 8-2) \u00e2\u20ac\u02dc&rsquo; La derni\u00e8re manche a \u00e9t\u00e9 tr\u00e8s stressante. Je ne savais pas que Cl\u00e9ment avait d\u00e0\u00bb abandonner et je ne le voyais plus sur le circuit. Dans les paddocks, on me panneautait en m&rsquo;indiquant que je devais prendre un maximum de points. Le circuit \u00e9tait tr\u00e8s difficile mais je me sentais nettement mieux que dans la premi\u00e8re manche. Heureusement, tout s&rsquo;est bien pass\u00e9 et nous avons pu l&#8217;emporter.\u00a0\u00bb<\/p>\n<p><img decoding=\"async\" class=\"lazyload alignnone size-full wp-image-19521\" title=\"Ken \\'Keeno\\' De Dijcker: bient\u00f4t une statue?\" src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/09\/ken-de-dijcker.jpg\" data-orig-src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/09\/ken-de-dijcker.jpg\" alt=\"\" width=\"500\" height=\"302\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27500%27%20height%3D%27302%27%20viewBox%3D%270%200%20500%20302%27%3E%3Crect%20width%3D%27500%27%20height%3D%27302%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/09\/ken-de-dijcker-300x181.jpg 300w, https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/09\/ken-de-dijcker.jpg 500w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n<p><strong>Cl\u00e9ment Desalle<\/strong> (Belgique : 1er &#8211; OPEN: 3) : \u00a0\u00bb C&rsquo;est dommage que je ne peux pas profiter \u00e0\u00a0 fond de notre victoire. Je suis content que nous ayons pu enfin remporter cette belle \u00e9preuve mais en m\u00eame temps, mon \u00e9paule me fait beaucoup souffrir. Ma premi\u00e8re manche s&rsquo;est bien pass\u00e9e m\u00eame si j&rsquo;ai connu quelques probl\u00e8mes au d\u00e9part. Lors de la derni\u00e8re manche, je suis tomb\u00e9 imm\u00e9diatement et j&rsquo;ai d\u00e0\u00bb abandonner. C&rsquo;est vraiment dommage que je me sois bless\u00e9 lors de la toute derni\u00e8re manche de la saison. Mais bon, je vais essayer de profiter au maximum de notre victoire ce soir et j&rsquo;irai demain chez le m\u00e9decin. Je tiens encore \u00e0\u00a0 f\u00e9liciter tout le team belge pour sa belle prestation.\u00a0\u00bb<\/p>\n<p><img decoding=\"async\" class=\"lazyload alignnone size-full wp-image-19518\" title=\"Cl\u00e9ment Desalle: une joie mitig\u00e9e \u00e0\u00a0 cause de sa blessure \u00e0\u00a0 l\\'\u00e9paule\" src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/09\/clement-desalle1.jpg\" data-orig-src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/09\/clement-desalle1.jpg\" alt=\"\" width=\"500\" height=\"333\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27500%27%20height%3D%27333%27%20viewBox%3D%270%200%20500%20333%27%3E%3Crect%20width%3D%27500%27%20height%3D%27333%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/09\/clement-desalle1-300x199.jpg 300w, https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/09\/clement-desalle1.jpg 500w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n<p><strong>Ryan Dungey<\/strong> (USA: 2\u00e8me &#8211; MX1 6-7): \u00a0\u00bbSans vouloir chercher des excuses, mon avion est arriv\u00e9 en provenance des Etats-Unis avec un retard de vingt-quatre heures sur l&rsquo;horaire pr\u00e9vu de sorte que j&rsquo;ai eu peu de temps pour reconna\u00eetre le circuit et m&rsquo;entra\u00eener. Nous nous sommes pourtant bien battus mais cela fait malgr\u00e9 tout la deuxi\u00e8me ann\u00e9e cons\u00e9cutive que nous ne remportons pas cette \u00e9preuve prestigieuse.\u00a0\u00bb<\/p>\n<p><img decoding=\"async\" class=\"lazyload alignnone size-full wp-image-19523\" title=\"Ryan Dungey: le maillon faible de l\\'\u00e9quipe US?\" src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/09\/ryan-dungey.jpg\" data-orig-src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/09\/ryan-dungey.jpg\" alt=\"\" width=\"500\" height=\"334\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27500%27%20height%3D%27334%27%20viewBox%3D%270%200%20500%20334%27%3E%3Crect%20width%3D%27500%27%20height%3D%27334%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/09\/ryan-dungey-300x200.jpg 300w, https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/09\/ryan-dungey.jpg 500w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n<p><strong>Toni Cairoli<\/strong> (Italie\u00a0: 3\u00e8me &#8211; Open 1-1)\u00a0:\u00a0\u00a0\u00bb Notre objectif \u00e9tait de monter sur le podium mais il y avait de nombreux teams qui pouvaient \u00e9galement y pr\u00e9tendre. Mon r\u00eave \u00e9tait un podium et c&rsquo;est la premi\u00e8re fois en huit ans que nous y avons droit. Pour nous, c&rsquo;\u00e9tait comme une victoire. Mon objectif personnel \u00e9tait de remporter deux victoires individuelles dans la cat\u00e9gorie MX1 et j&rsquo;y suis parvenu.\u00a0\u00bb<\/p>\n<p><img decoding=\"async\" class=\"lazyload alignnone size-full wp-image-19517\" title=\"Antonio Cairoli: d\u00e9cid\u00e9ment le \\'boss\\' du cross mondial\" src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/09\/antonio-cairoli.jpg\" data-orig-src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/09\/antonio-cairoli.jpg\" alt=\"\" width=\"500\" height=\"333\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27500%27%20height%3D%27333%27%20viewBox%3D%270%200%20500%20333%27%3E%3Crect%20width%3D%27500%27%20height%3D%27333%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/09\/antonio-cairoli-300x199.jpg 300w, https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/09\/antonio-cairoli.jpg 500w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n<p><strong>Alessandro Lupino<\/strong> (Italie: 3\u00e8me &#8211; MX2: 8-13): \u00ab\u00a0Ce week-end, j&rsquo;ai fait de nets progr\u00e8s en ce qui concerne les d\u00e9parts et c&rsquo;est important pour la prochaine saison. Mes chronos \u00e9taient bons et je me suis battu dans le top-dix dans les deux manches. C&rsquo;\u00e9tait super de figurer sur le podium avec le team Italie. Je voudrais remercier toutes les personnes qui ont travbaill\u00e9 avec moi cette saison.. Nos r\u00e9sultats n&rsquo;ont pas toujours \u00e9t\u00e9 \u00e0\u00a0 la hauteur de nos esp\u00e9rances mais nous savons ce que nous devons faire pour l&rsquo;ann\u00e9e prochaine.\u00a0\u00bb<\/p>\n<p><img decoding=\"async\" class=\"lazyload alignnone size-full wp-image-19515\" title=\"Alessandro Lupino s\\'est bien d\u00e9fendu dans l\\'\u00e9quipe d\\'Italie\" src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/09\/alessandro-lupino.jpg\" data-orig-src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/09\/alessandro-lupino.jpg\" alt=\"\" width=\"500\" height=\"333\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27500%27%20height%3D%27333%27%20viewBox%3D%270%200%20500%20333%27%3E%3Crect%20width%3D%27500%27%20height%3D%27333%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/09\/alessandro-lupino-300x199.jpg 300w, https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/09\/alessandro-lupino.jpg 500w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n<p><strong>Dean Ferris<\/strong> (Australie: 4\u00e8me &#8211; MX2: 4-5) : \u00ab\u00a0Cela aurait \u00e9t\u00e9 super de monter sur le podium mais mes co\u00e9quipiers ont vraiment fait le maximum aujourd&rsquo;hui et nous sommes litt\u00e9ralement lessiv\u00e9s. Je suis content de la mani\u00e8re avec laquelle j&rsquo;ai roul\u00e9. J&rsquo;ai effectu\u00e9 trois bons d\u00e9parts et je me suis retrouv\u00e9 dans le top-cinq toute la journ\u00e9e sans oublier que j&rsquo;ai termin\u00e9 premier dans la manche qualificative. Plus il y a d&rsquo;orni\u00e8res, mieux c&rsquo;est et plus c&rsquo;est technique, plus j&rsquo;aime \u00e7a, surtout quand la moto marche bien! C&rsquo;est probablement aujourd&rsquo;hui que j&rsquo;ai \u00e9t\u00e9 le plus rapide &#8211; apr\u00e8s un peu de testing cette semaine &#8211; et il n&rsquo;y a pas de raisons pour lesquelles je ne devrais pas aller de plus en plus vite avec ces r\u00e9glages.\u00a0\u00bb<\/p>\n<p><img decoding=\"async\" class=\"lazyload alignnone size-full wp-image-17970\" title=\"Dean Ferris et ses \u00e9quipiers \u00e9chouent au pied du podium\" src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/05\/dean-ferris1.jpg\" data-orig-src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/05\/dean-ferris1.jpg\" alt=\"\" width=\"498\" height=\"305\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27498%27%20height%3D%27305%27%20viewBox%3D%270%200%20498%20305%27%3E%3Crect%20width%3D%27498%27%20height%3D%27305%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/05\/dean-ferris1-300x183.jpg 300w, https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/05\/dean-ferris1.jpg 498w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 498px) 100vw, 498px\" \/><\/p>\n<p><strong>Gautier Paulin<\/strong> (France: 5\u00e8me &#8211; MX1: 5-6): \u00ab\u00a0Nous nous attendions \u00e0\u00a0 r\u00e9aliser un podium et nous sommes bien s\u00e0\u00bbr d\u00e9\u00e7us m\u00eame si chacun a fait le maximum dans le team France. Lors de ma premi\u00e8re course, mon d\u00e9part a \u00e9t\u00e9 moyen mais je suis remont\u00e9 \u00e0\u00a0 la cinqui\u00e8me place. J&rsquo;\u00e9tais proche de la quatri\u00e8me place lorsqu&rsquo;un pilote doubl\u00e9 s&rsquo;est mis dans mon chemin juste avant un saut de sorte que j&rsquo;ai pu m&rsquo;estimer heureux d.\u00eatre rest\u00e9 sur mes deux roues. Mon second d\u00e9part \u00e9tait bon mais au bout d&rsquo;un demi tour, je me suis retrouv\u00e9 avec une pierre dans le frein arri\u00e8re et j&rsquo;ai connu des probl\u00e8mes pendant quelques tours. Je savais que nous ne pourrions pas monter sur le podium quel que soit mon r\u00e9sultat mais j&rsquo;ai contenu Dungey pour terminer sixi\u00e8me.\u00a0\u00bb<\/p>\n<p><a href=\"Aucune\"><img decoding=\"async\" class=\"lazyload alignnone size-full wp-image-18358\" title=\"Gautier Paulin s\\'attendait \u00e0\u00a0 un podium pour l\\'\u00e9quipe de France\" src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/07\/gautier-paulin.jpg\" data-orig-src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/07\/gautier-paulin.jpg\" alt=\"\" width=\"500\" height=\"315\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27500%27%20height%3D%27315%27%20viewBox%3D%270%200%20500%20315%27%3E%3Crect%20width%3D%27500%27%20height%3D%27315%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/07\/gautier-paulin-300x189.jpg 300w, https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/07\/gautier-paulin.jpg 500w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p><strong>Tommy Searle<\/strong> (Royaume-Uni: 6\u00e8me &#8211; MX1: 3-5): \u00ab\u00a0Terminer troisi\u00e8me et cinqui\u00e8me dans une \u00e9preuve comme le Motocross desNations, c&rsquo;est une superbe mani\u00e8re de cl\u00f4turer la saison. Nous passerons l&rsquo;arri\u00e8re-saison avec confiance compte tenu que nous avons fait de bons progr\u00e8s sur la moto. Nous n&rsquo;avons eu qu&rsquo;une journ\u00e9e pour tester des suspensions WP qui n&rsquo;avaient jamais vraiment \u00e9t\u00e9 test\u00e9es sur une Kawasaki dans le pass\u00e9 et nous sommes parvenus \u00e0\u00a0 r\u00e9ussir une deuxi\u00e8me place en MX1 dans le cadre de l&rsquo;\u00e9preuve la plus prestigieuse de l&rsquo;ann\u00e9e. Le circuit \u00e9tait vraiment un des plus durs sur lesquels j&rsquo;aie jamais roul\u00e9 mais c&rsquo;\u00e9tait un super week-end. J&rsquo;ai vraiment appr\u00e9ci\u00e9 l&rsquo;ambiance cr\u00e9\u00e9e par tous nos supporters qui n&rsquo;avaient pas h\u00e9sit\u00e9 \u00e0\u00a0 venir \u00e0\u00a0 Teutschenthal.\u00a0\u00bb<\/p>\n<p><img decoding=\"async\" class=\"lazyload alignnone size-full wp-image-19524\" title=\"Tommy Searle \u00e9tait satisfait de sa prestation\" src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/09\/tommy-searle2.jpg\" data-orig-src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/09\/tommy-searle2.jpg\" alt=\"\" width=\"500\" height=\"333\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27500%27%20height%3D%27333%27%20viewBox%3D%270%200%20500%20333%27%3E%3Crect%20width%3D%27500%27%20height%3D%27333%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/09\/tommy-searle2-300x199.jpg 300w, https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/09\/tommy-searle2.jpg 500w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n<p><strong>Ken Roczen<\/strong> (Allemagne: 7\u00e8me &#8211; MX2 2-1)\u00a0: \u00ab\u00a0Je n&rsquo;\u00e9tais pas vraiment \u00e0\u00a0 l&rsquo;aise lors de la premi\u00e8re manche mais j&rsquo;ai r\u00e9ussi un bon d\u00e9part dans la seconde manche et Eli (Tomac) et moi, nous nous sommes battus du d\u00e9but jusqu&rsquo;\u00e0\u00a0 la fin. C&rsquo;\u00e9tait important pour moi de remporter une manche et dans l&rsquo;ensemble, je suis content de mes r\u00e9sultats. J&rsquo;ai atteint mon objectif personnel et mes supporters ont \u00e9t\u00e9 formidables!\u00a0\u00bb<\/p>\n<p><img decoding=\"async\" class=\"lazyload alignnone size-full wp-image-13804\" title=\"Ken Roczen: une bonne performance individuelle \" src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2011\/12\/roczen_portrait.jpg\" data-orig-src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2011\/12\/roczen_portrait.jpg\" alt=\"\" width=\"500\" height=\"334\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27500%27%20height%3D%27334%27%20viewBox%3D%270%200%20500%20334%27%3E%3Crect%20width%3D%27500%27%20height%3D%27334%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2011\/12\/roczen_portrait-300x200.jpg 300w, https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2011\/12\/roczen_portrait.jpg 500w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le motocross reste un sport extr\u00eamement populaire comme on a pu encore le constater ce week-end \u00e0\u00a0 Teutschenthal, en Allemagne. En effet, m\u00eame s&rsquo;il faut se m\u00e9fier des estimations &#8211; [&#8230;]<\/p>\n","protected":false},"author":898,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,6,65],"tags":[],"class_list":["post-19514","post","type-post","status-publish","format-standard","hentry","category-motocross","category-mx1mx2","category-slideshow"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Motocross des Nations - Teutschenthal | Les r\u00e9actions des pilotes - Motocross - Enduro - Supermoto | MotocrossMag<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fr.motocrossmag.be\/index.php\/2013\/09\/motocross-des-nations-teutschenthal-les-reactions-des-pilotes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Motocross des Nations - Teutschenthal | Les r\u00e9actions des pilotes - Motocross - Enduro - Supermoto | MotocrossMag\" \/>\n<meta property=\"og:description\" content=\"Le motocross reste un sport extr\u00eamement populaire comme on a pu encore le constater ce week-end \u00e0\u00a0 Teutschenthal, en Allemagne. En effet, m\u00eame s&rsquo;il faut se m\u00e9fier des estimations &#8211; [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fr.motocrossmag.be\/index.php\/2013\/09\/motocross-des-nations-teutschenthal-les-reactions-des-pilotes\/\" \/>\n<meta property=\"og:site_name\" content=\"Motocross - Enduro - Supermoto | MotocrossMag\" \/>\n<meta property=\"article:published_time\" content=\"2013-09-30T15:02:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-09-30T22:02:05+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/09\/la-foule.jpg\" \/>\n<meta name=\"author\" content=\"fernand2\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"fernand2\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2013\\\/09\\\/motocross-des-nations-teutschenthal-les-reactions-des-pilotes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2013\\\/09\\\/motocross-des-nations-teutschenthal-les-reactions-des-pilotes\\\/\"},\"author\":{\"name\":\"fernand2\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#\\\/schema\\\/person\\\/b1bd0a25696c3aeaac7fd5d92d4ed8f6\"},\"headline\":\"Motocross des Nations &#8211; Teutschenthal | Les r\u00e9actions des pilotes\",\"datePublished\":\"2013-09-30T15:02:56+00:00\",\"dateModified\":\"2013-09-30T22:02:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2013\\\/09\\\/motocross-des-nations-teutschenthal-les-reactions-des-pilotes\\\/\"},\"wordCount\":1599,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2013\\\/09\\\/motocross-des-nations-teutschenthal-les-reactions-des-pilotes\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/fr.motocrossmag.be\\\/wp-content\\\/uploads\\\/2013\\\/09\\\/la-foule.jpg\",\"articleSection\":[\"Motocross\",\"Motocross MXGP\",\"Slideshow\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2013\\\/09\\\/motocross-des-nations-teutschenthal-les-reactions-des-pilotes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2013\\\/09\\\/motocross-des-nations-teutschenthal-les-reactions-des-pilotes\\\/\",\"url\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2013\\\/09\\\/motocross-des-nations-teutschenthal-les-reactions-des-pilotes\\\/\",\"name\":\"Motocross des Nations - Teutschenthal | Les r\u00e9actions des pilotes - Motocross - Enduro - Supermoto | MotocrossMag\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2013\\\/09\\\/motocross-des-nations-teutschenthal-les-reactions-des-pilotes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2013\\\/09\\\/motocross-des-nations-teutschenthal-les-reactions-des-pilotes\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/fr.motocrossmag.be\\\/wp-content\\\/uploads\\\/2013\\\/09\\\/la-foule.jpg\",\"datePublished\":\"2013-09-30T15:02:56+00:00\",\"dateModified\":\"2013-09-30T22:02:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#\\\/schema\\\/person\\\/b1bd0a25696c3aeaac7fd5d92d4ed8f6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2013\\\/09\\\/motocross-des-nations-teutschenthal-les-reactions-des-pilotes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2013\\\/09\\\/motocross-des-nations-teutschenthal-les-reactions-des-pilotes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2013\\\/09\\\/motocross-des-nations-teutschenthal-les-reactions-des-pilotes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fr.motocrossmag.be\\\/wp-content\\\/uploads\\\/2013\\\/09\\\/la-foule.jpg\",\"contentUrl\":\"https:\\\/\\\/fr.motocrossmag.be\\\/wp-content\\\/uploads\\\/2013\\\/09\\\/la-foule.jpg\",\"width\":500,\"height\":333},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2013\\\/09\\\/motocross-des-nations-teutschenthal-les-reactions-des-pilotes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/fr.motocrossmag.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Motocross des Nations &#8211; Teutschenthal | Les r\u00e9actions des pilotes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#website\",\"url\":\"https:\\\/\\\/fr.motocrossmag.be\\\/\",\"name\":\"Motocross - Enduro - Supermoto | MotocrossMag\",\"description\":\"L&#039;actualit\u00e9 du motocross, de l&#039;enduro et du Supermoto en ligne!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fr.motocrossmag.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#\\\/schema\\\/person\\\/b1bd0a25696c3aeaac7fd5d92d4ed8f6\",\"name\":\"fernand2\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e48cfba345f89620e0c3f40fdfd6f6ef6bc1fbad5d0c3cd2555b4f39e37ef934?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e48cfba345f89620e0c3f40fdfd6f6ef6bc1fbad5d0c3cd2555b4f39e37ef934?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e48cfba345f89620e0c3f40fdfd6f6ef6bc1fbad5d0c3cd2555b4f39e37ef934?s=96&d=mm&r=g\",\"caption\":\"fernand2\"},\"url\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/author\\\/fernand2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Motocross des Nations - Teutschenthal | Les r\u00e9actions des pilotes - Motocross - Enduro - Supermoto | MotocrossMag","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fr.motocrossmag.be\/index.php\/2013\/09\/motocross-des-nations-teutschenthal-les-reactions-des-pilotes\/","og_locale":"fr_FR","og_type":"article","og_title":"Motocross des Nations - Teutschenthal | Les r\u00e9actions des pilotes - Motocross - Enduro - Supermoto | MotocrossMag","og_description":"Le motocross reste un sport extr\u00eamement populaire comme on a pu encore le constater ce week-end \u00e0\u00a0 Teutschenthal, en Allemagne. En effet, m\u00eame s&rsquo;il faut se m\u00e9fier des estimations &#8211; [...]","og_url":"https:\/\/fr.motocrossmag.be\/index.php\/2013\/09\/motocross-des-nations-teutschenthal-les-reactions-des-pilotes\/","og_site_name":"Motocross - Enduro - Supermoto | MotocrossMag","article_published_time":"2013-09-30T15:02:56+00:00","article_modified_time":"2013-09-30T22:02:05+00:00","og_image":[{"url":"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/09\/la-foule.jpg","type":"","width":"","height":""}],"author":"fernand2","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"fernand2","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fr.motocrossmag.be\/index.php\/2013\/09\/motocross-des-nations-teutschenthal-les-reactions-des-pilotes\/#article","isPartOf":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2013\/09\/motocross-des-nations-teutschenthal-les-reactions-des-pilotes\/"},"author":{"name":"fernand2","@id":"https:\/\/fr.motocrossmag.be\/#\/schema\/person\/b1bd0a25696c3aeaac7fd5d92d4ed8f6"},"headline":"Motocross des Nations &#8211; Teutschenthal | Les r\u00e9actions des pilotes","datePublished":"2013-09-30T15:02:56+00:00","dateModified":"2013-09-30T22:02:05+00:00","mainEntityOfPage":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2013\/09\/motocross-des-nations-teutschenthal-les-reactions-des-pilotes\/"},"wordCount":1599,"commentCount":0,"image":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2013\/09\/motocross-des-nations-teutschenthal-les-reactions-des-pilotes\/#primaryimage"},"thumbnailUrl":"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/09\/la-foule.jpg","articleSection":["Motocross","Motocross MXGP","Slideshow"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fr.motocrossmag.be\/index.php\/2013\/09\/motocross-des-nations-teutschenthal-les-reactions-des-pilotes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fr.motocrossmag.be\/index.php\/2013\/09\/motocross-des-nations-teutschenthal-les-reactions-des-pilotes\/","url":"https:\/\/fr.motocrossmag.be\/index.php\/2013\/09\/motocross-des-nations-teutschenthal-les-reactions-des-pilotes\/","name":"Motocross des Nations - Teutschenthal | Les r\u00e9actions des pilotes - Motocross - Enduro - Supermoto | MotocrossMag","isPartOf":{"@id":"https:\/\/fr.motocrossmag.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2013\/09\/motocross-des-nations-teutschenthal-les-reactions-des-pilotes\/#primaryimage"},"image":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2013\/09\/motocross-des-nations-teutschenthal-les-reactions-des-pilotes\/#primaryimage"},"thumbnailUrl":"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/09\/la-foule.jpg","datePublished":"2013-09-30T15:02:56+00:00","dateModified":"2013-09-30T22:02:05+00:00","author":{"@id":"https:\/\/fr.motocrossmag.be\/#\/schema\/person\/b1bd0a25696c3aeaac7fd5d92d4ed8f6"},"breadcrumb":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2013\/09\/motocross-des-nations-teutschenthal-les-reactions-des-pilotes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fr.motocrossmag.be\/index.php\/2013\/09\/motocross-des-nations-teutschenthal-les-reactions-des-pilotes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/fr.motocrossmag.be\/index.php\/2013\/09\/motocross-des-nations-teutschenthal-les-reactions-des-pilotes\/#primaryimage","url":"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/09\/la-foule.jpg","contentUrl":"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2013\/09\/la-foule.jpg","width":500,"height":333},{"@type":"BreadcrumbList","@id":"https:\/\/fr.motocrossmag.be\/index.php\/2013\/09\/motocross-des-nations-teutschenthal-les-reactions-des-pilotes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/fr.motocrossmag.be\/"},{"@type":"ListItem","position":2,"name":"Motocross des Nations &#8211; Teutschenthal | Les r\u00e9actions des pilotes"}]},{"@type":"WebSite","@id":"https:\/\/fr.motocrossmag.be\/#website","url":"https:\/\/fr.motocrossmag.be\/","name":"Motocross - Enduro - Supermoto | MotocrossMag","description":"L&#039;actualit\u00e9 du motocross, de l&#039;enduro et du Supermoto en ligne!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fr.motocrossmag.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/fr.motocrossmag.be\/#\/schema\/person\/b1bd0a25696c3aeaac7fd5d92d4ed8f6","name":"fernand2","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/e48cfba345f89620e0c3f40fdfd6f6ef6bc1fbad5d0c3cd2555b4f39e37ef934?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e48cfba345f89620e0c3f40fdfd6f6ef6bc1fbad5d0c3cd2555b4f39e37ef934?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e48cfba345f89620e0c3f40fdfd6f6ef6bc1fbad5d0c3cd2555b4f39e37ef934?s=96&d=mm&r=g","caption":"fernand2"},"url":"https:\/\/fr.motocrossmag.be\/index.php\/author\/fernand2\/"}]}},"_links":{"self":[{"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/posts\/19514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/users\/898"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/comments?post=19514"}],"version-history":[{"count":0,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/posts\/19514\/revisions"}],"wp:attachment":[{"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/media?parent=19514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/categories?post=19514"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/tags?post=19514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}