{"id":27825,"date":"2014-10-03T21:34:20","date_gmt":"2014-10-03T19:34:20","guid":{"rendered":"http:\/\/fr.motocrossmag.be\/?p=27825"},"modified":"2014-10-03T21:37:48","modified_gmt":"2014-10-03T19:37:48","slug":"coupe-de-lavenir-quelles-chances-pour-la-belgique","status":"publish","type":"post","link":"https:\/\/fr.motocrossmag.be\/index.php\/2014\/10\/coupe-de-lavenir-quelles-chances-pour-la-belgique\/","title":{"rendered":"Coupe de l&rsquo;Avenir: quelles chances pour la Belgique ?"},"content":{"rendered":"<p>Battue par la France en 2011, l&rsquo;\u00e9quipe belge avait reconquis son titre d\u00e8s l&rsquo;ann\u00e9e suivante en s&rsquo;imposant en octobre 2012 dans la 41\u00e8me Coupe de l&rsquo;Avenir. Un titre reconduit\u00a0 en 2013. Deux \u00e9ditions o\u00f9 le succ\u00e8s belge avait \u00e9t\u00e9 brilamment compl\u00e9t\u00e9 par les victoires individuelles de Yerki Janvier (2012) puis de Julien Van Stippen l&rsquo;an pass\u00e9. La Belgique peut-elle r\u00eaver \u00e0 une nouvelle prolongation de son brevet d&rsquo;invincibilit\u00e9 ce week-end ?<\/p>\n<p>Le rideau s&rsquo;appr\u00eate \u00e0 tomber sur la saison 2014 de motocross. Mais avant l&rsquo;hiver,un \u00e9v\u00e9nement majeur de notre calendrier cl\u00f4turera la saison en beaut\u00e9. Il s&rsquo;agit de la Coupe de l&rsquo;Avenir, disput\u00e9e ce week-end \u00e0 Baisieux, dans la commune de Qui\u00e9vrain et organis\u00e9e de main de ma\u00eetre par le Club Hauts-Pays.<\/p><div class=\"mgixc6a97db8f578d7\" ><!-- \/91277017\/Inline-articles-mobile -->\n<div style=\"margin:auto; text-align:center !important\">\n<div id='div-gpt-ad-1784982661365-0' style='min-width: 250px; min-height: 75px;'>\n  <script>\n    googletag.cmd.push(function() { googletag.display('div-gpt-ad-1784982661365-0'); });\n  <\/script>\n<\/div><\/div><\/div><style type=\"text\/css\">\r\n.mgixc6a97db8f578d7 {\r\nmargin-bottom:30px;margin-top:20px\r\n}\r\n@media screen and (min-width: 1201px) {\r\n.mgixc6a97db8f578d7 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.mgixc6a97db8f578d7 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.mgixc6a97db8f578d7 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.mgixc6a97db8f578d7 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.mgixc6a97db8f578d7 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n\n<p>Pour d\u00e9fendre nos couleurs, Robert Gielis et Yves Devlaminck ont fait confiance \u00e0 Ludovic Brevers, Brent Van Doninck et Cyril Genot. Un trio prometteur qui semble assez logique au vu de la saison \u00e9coul\u00e9e. Van Doninck et Genot ont \u00e9t\u00e9 nos meilleurs repr\u00e9sentants cette saison respectivement en championnat EMX 250 et EMX 125, tandis que Ludovic Brevers a prouv\u00e9 ces derni\u00e8res semaines avoir d\u00e9j\u00e0 retrouv\u00e9 la grande forme apr\u00e8s pourtant pr\u00e8s de 18 mois sans comp\u00e9tition.<\/p>\n<p><strong>Un trio en forme<\/strong><\/p>\n<p>\u201cNous n\u2019avons pas s\u00e9lectionn\u00e9 de pilotes de Grand Prix, explique Robert Gielis. Ils ont d\u00e9j\u00e0 suffisamment d\u2019opportunit\u00e9s. Nous avons choisi des pilotes qui ont particip\u00e9 aux championnats europ\u00e9ens et belges, en fonction de leurs r\u00e9sultats \u00e0 ces comp\u00e9titions. Nous avons attendu le milieu de saison avant de s\u00e9lectionner les pilotes. Cela nous a permis de voir qui \u00e9tait encore en forme. Le choix de Brent Van doninck (cinqui\u00e8me au championnat europ\u00e9en 250cc) \u00e9tait une \u00e9vidence. Quant \u00e0 Cyril Genot, il fait partie de nos jeunes talents. Ludovic Brevers, longtemps bless\u00e9, est remont\u00e9 en selle il y deux mois. Il a progressivement retrouv\u00e9 sa forme exceptionnelle, pr\u00e9cise Gielis. Nous pensons que ces trois coureurs sont un choix logique pour la cat\u00e9gorie MX2.\u00a0\u00bb<\/p><div class=\"jjgfm6a97db8f578ec\" ><!-- \/91277017\/articles-inline-2 -->\n<div style=\"margin: 20px auto; text-align:center !important\">\n<div id='div-gpt-ad-1785021530385-0' style='min-width: 300px; min-height: 75px;'>\n  <script>\n    googletag.cmd.push(function() { googletag.display('div-gpt-ad-1785021530385-0'); });\n  <\/script>\n<\/div><\/div><\/div><style type=\"text\/css\">\r\n@media screen and (min-width: 1201px) {\r\n.jjgfm6a97db8f578ec {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.jjgfm6a97db8f578ec {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.jjgfm6a97db8f578ec {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.jjgfm6a97db8f578ec {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.jjgfm6a97db8f578ec {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n\n<figure id=\"attachment_27828\" aria-describedby=\"caption-attachment-27828\" style=\"width: 650px\" class=\"wp-caption alignnone\"><img decoding=\"async\" class=\"size-full wp-image-27828\" src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2014\/10\/brevers_ludovic_orp_2014.jpg\" alt=\"Esp\u00e9rons que Ludovic Brevers pourra confirmer ce week-end \u00e0 Baisieux son retour en forme !\" width=\"650\" height=\"433\" \/><figcaption id=\"caption-attachment-27828\" class=\"wp-caption-text\">Esp\u00e9rons que Ludovic Brevers pourra confirmer ce week-end \u00e0 Baisieux son retour en forme !<\/figcaption><\/figure>\n<p>Quelles sont les chances de l&rsquo;\u00e9quipe belge ? Gielis : \u201cAu vu de la liste des pays participants, je pense que nous devons absolument viser la victoire. Nos principaux concurrents seront les Fran\u00e7ais, mais aussi les Finlandais qui, je pense, seront tr\u00e8s forts.\u00a0\u00bb<\/p>\n<p><strong>Liam Everts en 65cc<\/strong><\/p>\n<p>L\u2019\u00e9preuve se d\u00e9roulera sur le circuit de la Ferme des Monts \u00e0 Baisieux-Qui\u00e9vrain, un site id\u00e9al et vallonn\u00e9 \u00e0 souhait. Le niveau de difficult\u00e9 est adapt\u00e9 au niveau des jeunes participants. \u00ab\u00a0Le trac\u00e9 n\u2019est pas aussi exigeant qu\u2019\u00e0 Lierneux, o\u00f9 s\u2019est d\u00e9roul\u00e9 le championnat du monde junior en ao\u00fbt dernier. L\u00e0-bas, les distances de jumps \u00e9taient tr\u00e8s longues et le circuit \u00e9tait digne d\u2019un Grand Prix. Le parcours de dimanche est \u00e9galement abordable pour les cat\u00e9gories 65 et 85cc.\u00a0\u00bb, termine Robert Gielis.<\/p>\n<p>Car oui, en marge de la Coupe de l&rsquo;Avenir, se disputeront \u00e9galement une Coupe 85cc ainsi que, c&rsquo;est une premi\u00e8re, une Coupe 65cc. Une cat\u00e9gorie pour laquelle nous n&rsquo;avons en Belgique pas de championnat officiel mais dans laquelle on retrouvera sous nos couleurs ce week-end un certain Liam Everts !<\/p>\n<p>Cette semaine, les pilotes ont particip\u00e9 \u00e0 une derni\u00e8re journ\u00e9e de stage sous la houlette d&rsquo;Yves Devlaminck. De quoi souder l&rsquo;\u00e9quipe et aborder la Coupe de l&rsquo;Avenir dans les meilleures dispositions qui soient. Et esp\u00e9rer porter tr\u00e8s haut les couleurs belges ce week-end \u00e0 Baisieux !<\/p>\n<p><a href=\"http:\/\/www.coupedelavenir.be\" target=\"_blank\">&gt; www.coupedelavenir.be<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Battue par la France en 2011, l&rsquo;\u00e9quipe belge avait reconquis son titre d\u00e8s l&rsquo;ann\u00e9e suivante en s&rsquo;imposant en octobre 2012 dans la 41\u00e8me Coupe de l&rsquo;Avenir. Un titre reconduit\u00a0 en 2013. Deux \u00e9ditions o\u00f9 le succ\u00e8s belge avait \u00e9t\u00e9 brilamment compl\u00e9t\u00e9 par les victoires individuelles de Yerki Janvier (2012) puis de Julien Van Stippen l&rsquo;an [&hellip;]<\/p>\n","protected":false},"author":932,"featured_media":27826,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[54,4,29,5,55,65],"tags":[],"class_list":["post-27825","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualite","category-motocross","category-fmb","category-news","category-news-actualite","category-slideshow"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Coupe de l&#039;Avenir: quelles chances pour la Belgique ? - Motocross - Enduro - Supermoto | MotocrossMag<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fr.motocrossmag.be\/index.php\/2014\/10\/coupe-de-lavenir-quelles-chances-pour-la-belgique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coupe de l&#039;Avenir: quelles chances pour la Belgique ? - Motocross - Enduro - Supermoto | MotocrossMag\" \/>\n<meta property=\"og:description\" content=\"Battue par la France en 2011, l&rsquo;\u00e9quipe belge avait reconquis son titre d\u00e8s l&rsquo;ann\u00e9e suivante en s&rsquo;imposant en octobre 2012 dans la 41\u00e8me Coupe de l&rsquo;Avenir. Un titre reconduit\u00a0 en 2013. Deux \u00e9ditions o\u00f9 le succ\u00e8s belge avait \u00e9t\u00e9 brilamment compl\u00e9t\u00e9 par les victoires individuelles de Yerki Janvier (2012) puis de Julien Van Stippen l&rsquo;an [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fr.motocrossmag.be\/index.php\/2014\/10\/coupe-de-lavenir-quelles-chances-pour-la-belgique\/\" \/>\n<meta property=\"og:site_name\" content=\"Motocross - Enduro - Supermoto | MotocrossMag\" \/>\n<meta property=\"article:published_time\" content=\"2014-10-03T19:34:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-10-03T19:37:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2014\/10\/genot_cyril.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"433\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"oliviere\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"oliviere\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2014\\\/10\\\/coupe-de-lavenir-quelles-chances-pour-la-belgique\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2014\\\/10\\\/coupe-de-lavenir-quelles-chances-pour-la-belgique\\\/\"},\"author\":{\"name\":\"oliviere\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#\\\/schema\\\/person\\\/11b47143d9f755babca2c9110e03235c\"},\"headline\":\"Coupe de l&rsquo;Avenir: quelles chances pour la Belgique ?\",\"datePublished\":\"2014-10-03T19:34:20+00:00\",\"dateModified\":\"2014-10-03T19:37:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2014\\\/10\\\/coupe-de-lavenir-quelles-chances-pour-la-belgique\\\/\"},\"wordCount\":629,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2014\\\/10\\\/coupe-de-lavenir-quelles-chances-pour-la-belgique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fr.motocrossmag.be\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/genot_cyril.jpg\",\"articleSection\":[\"Actualit\u00e9\",\"Motocross\",\"Motocross FMB\",\"News\",\"News\",\"Slideshow\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2014\\\/10\\\/coupe-de-lavenir-quelles-chances-pour-la-belgique\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2014\\\/10\\\/coupe-de-lavenir-quelles-chances-pour-la-belgique\\\/\",\"url\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2014\\\/10\\\/coupe-de-lavenir-quelles-chances-pour-la-belgique\\\/\",\"name\":\"Coupe de l'Avenir: quelles chances pour la Belgique ? - Motocross - Enduro - Supermoto | MotocrossMag\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2014\\\/10\\\/coupe-de-lavenir-quelles-chances-pour-la-belgique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2014\\\/10\\\/coupe-de-lavenir-quelles-chances-pour-la-belgique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fr.motocrossmag.be\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/genot_cyril.jpg\",\"datePublished\":\"2014-10-03T19:34:20+00:00\",\"dateModified\":\"2014-10-03T19:37:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#\\\/schema\\\/person\\\/11b47143d9f755babca2c9110e03235c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2014\\\/10\\\/coupe-de-lavenir-quelles-chances-pour-la-belgique\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2014\\\/10\\\/coupe-de-lavenir-quelles-chances-pour-la-belgique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2014\\\/10\\\/coupe-de-lavenir-quelles-chances-pour-la-belgique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fr.motocrossmag.be\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/genot_cyril.jpg\",\"contentUrl\":\"https:\\\/\\\/fr.motocrossmag.be\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/genot_cyril.jpg\",\"width\":650,\"height\":433},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2014\\\/10\\\/coupe-de-lavenir-quelles-chances-pour-la-belgique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/fr.motocrossmag.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coupe de l&rsquo;Avenir: quelles chances pour la Belgique ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#website\",\"url\":\"https:\\\/\\\/fr.motocrossmag.be\\\/\",\"name\":\"Motocross - Enduro - Supermoto | MotocrossMag\",\"description\":\"L&#039;actualit\u00e9 du motocross, de l&#039;enduro et du Supermoto en ligne!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fr.motocrossmag.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#\\\/schema\\\/person\\\/11b47143d9f755babca2c9110e03235c\",\"name\":\"oliviere\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g\",\"caption\":\"oliviere\"},\"sameAs\":[\"http:\\\/\\\/www.motocrossmag.be\"],\"url\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/author\\\/oliviere\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Coupe de l'Avenir: quelles chances pour la Belgique ? - Motocross - Enduro - Supermoto | MotocrossMag","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fr.motocrossmag.be\/index.php\/2014\/10\/coupe-de-lavenir-quelles-chances-pour-la-belgique\/","og_locale":"fr_FR","og_type":"article","og_title":"Coupe de l'Avenir: quelles chances pour la Belgique ? - Motocross - Enduro - Supermoto | MotocrossMag","og_description":"Battue par la France en 2011, l&rsquo;\u00e9quipe belge avait reconquis son titre d\u00e8s l&rsquo;ann\u00e9e suivante en s&rsquo;imposant en octobre 2012 dans la 41\u00e8me Coupe de l&rsquo;Avenir. Un titre reconduit\u00a0 en 2013. Deux \u00e9ditions o\u00f9 le succ\u00e8s belge avait \u00e9t\u00e9 brilamment compl\u00e9t\u00e9 par les victoires individuelles de Yerki Janvier (2012) puis de Julien Van Stippen l&rsquo;an [&hellip;]","og_url":"https:\/\/fr.motocrossmag.be\/index.php\/2014\/10\/coupe-de-lavenir-quelles-chances-pour-la-belgique\/","og_site_name":"Motocross - Enduro - Supermoto | MotocrossMag","article_published_time":"2014-10-03T19:34:20+00:00","article_modified_time":"2014-10-03T19:37:48+00:00","og_image":[{"width":650,"height":433,"url":"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2014\/10\/genot_cyril.jpg","type":"image\/jpeg"}],"author":"oliviere","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"oliviere","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fr.motocrossmag.be\/index.php\/2014\/10\/coupe-de-lavenir-quelles-chances-pour-la-belgique\/#article","isPartOf":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2014\/10\/coupe-de-lavenir-quelles-chances-pour-la-belgique\/"},"author":{"name":"oliviere","@id":"https:\/\/fr.motocrossmag.be\/#\/schema\/person\/11b47143d9f755babca2c9110e03235c"},"headline":"Coupe de l&rsquo;Avenir: quelles chances pour la Belgique ?","datePublished":"2014-10-03T19:34:20+00:00","dateModified":"2014-10-03T19:37:48+00:00","mainEntityOfPage":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2014\/10\/coupe-de-lavenir-quelles-chances-pour-la-belgique\/"},"wordCount":629,"commentCount":0,"image":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2014\/10\/coupe-de-lavenir-quelles-chances-pour-la-belgique\/#primaryimage"},"thumbnailUrl":"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2014\/10\/genot_cyril.jpg","articleSection":["Actualit\u00e9","Motocross","Motocross FMB","News","News","Slideshow"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fr.motocrossmag.be\/index.php\/2014\/10\/coupe-de-lavenir-quelles-chances-pour-la-belgique\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fr.motocrossmag.be\/index.php\/2014\/10\/coupe-de-lavenir-quelles-chances-pour-la-belgique\/","url":"https:\/\/fr.motocrossmag.be\/index.php\/2014\/10\/coupe-de-lavenir-quelles-chances-pour-la-belgique\/","name":"Coupe de l'Avenir: quelles chances pour la Belgique ? - Motocross - Enduro - Supermoto | MotocrossMag","isPartOf":{"@id":"https:\/\/fr.motocrossmag.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2014\/10\/coupe-de-lavenir-quelles-chances-pour-la-belgique\/#primaryimage"},"image":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2014\/10\/coupe-de-lavenir-quelles-chances-pour-la-belgique\/#primaryimage"},"thumbnailUrl":"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2014\/10\/genot_cyril.jpg","datePublished":"2014-10-03T19:34:20+00:00","dateModified":"2014-10-03T19:37:48+00:00","author":{"@id":"https:\/\/fr.motocrossmag.be\/#\/schema\/person\/11b47143d9f755babca2c9110e03235c"},"breadcrumb":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2014\/10\/coupe-de-lavenir-quelles-chances-pour-la-belgique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fr.motocrossmag.be\/index.php\/2014\/10\/coupe-de-lavenir-quelles-chances-pour-la-belgique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/fr.motocrossmag.be\/index.php\/2014\/10\/coupe-de-lavenir-quelles-chances-pour-la-belgique\/#primaryimage","url":"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2014\/10\/genot_cyril.jpg","contentUrl":"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2014\/10\/genot_cyril.jpg","width":650,"height":433},{"@type":"BreadcrumbList","@id":"https:\/\/fr.motocrossmag.be\/index.php\/2014\/10\/coupe-de-lavenir-quelles-chances-pour-la-belgique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/fr.motocrossmag.be\/"},{"@type":"ListItem","position":2,"name":"Coupe de l&rsquo;Avenir: quelles chances pour la Belgique ?"}]},{"@type":"WebSite","@id":"https:\/\/fr.motocrossmag.be\/#website","url":"https:\/\/fr.motocrossmag.be\/","name":"Motocross - Enduro - Supermoto | MotocrossMag","description":"L&#039;actualit\u00e9 du motocross, de l&#039;enduro et du Supermoto en ligne!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fr.motocrossmag.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/fr.motocrossmag.be\/#\/schema\/person\/11b47143d9f755babca2c9110e03235c","name":"oliviere","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g","caption":"oliviere"},"sameAs":["http:\/\/www.motocrossmag.be"],"url":"https:\/\/fr.motocrossmag.be\/index.php\/author\/oliviere\/"}]}},"_links":{"self":[{"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/posts\/27825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/users\/932"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/comments?post=27825"}],"version-history":[{"count":3,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/posts\/27825\/revisions"}],"predecessor-version":[{"id":27831,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/posts\/27825\/revisions\/27831"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/media\/27826"}],"wp:attachment":[{"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/media?parent=27825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/categories?post=27825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/tags?post=27825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}