{"id":41227,"date":"2015-12-10T15:18:35","date_gmt":"2015-12-10T14:18:35","guid":{"rendered":"http:\/\/fr.motocrossmag.be\/?p=41227"},"modified":"2015-12-10T15:33:35","modified_gmt":"2015-12-10T14:33:35","slug":"bud-racing-sur-tous-les-fronts","status":"publish","type":"post","link":"https:\/\/fr.motocrossmag.be\/index.php\/2015\/12\/bud-racing-sur-tous-les-fronts\/","title":{"rendered":"Bud Racing sur tous les fronts"},"content":{"rendered":"<p>Le team Kawasaki Bud Racing se pr\u00e9pare \u00e0 un programme 2016 pour le moins charg\u00e9. Pas moins de 7 pilotes porteront les couleurs du team fran\u00e7ais avec des programmes qui s&rsquo;\u00e9tendent tant en Europe qu&rsquo;aux USA ! Si Xavier Boog sera fid\u00e8le au championnat de France Elite dans la cat\u00e9gorie MX1 o\u00f9 il d\u00e9fendra son titre et fera \u00e9quipe avec Maxime Desprey, Nicolas Dercourt, qui r\u00e9cup\u00e8re actuellement d&rsquo;une blessure au genou, roulera lui aussi en championnat de France Elite mais dans la classe MX2.<\/p>\n<p>Mais le programme sportif de Bud Racing s&rsquo;\u00e9tend bien au-del\u00e0 des fronti\u00e8res de l&rsquo;hexagone puisque Desprey et Sanayei disputeront le championnat SX US en 250 sur la c\u00f4te Ouest ! Darian Sanayei, nouveau venu chez Bud et d\u00e9j\u00e0 vainqueur d&rsquo;une manche en 2015 sur le championnat US SX Lite, sera \u00e9galement sur le championnat d&rsquo;Europe 250cc aux c\u00f4t\u00e9s de Nicolas Dercourt.<\/p>\n<p>Bud Racing mise aussi sur l&rsquo;avenir avec Brian Moreau sur le championnat d&rsquo;Europe 125cc ainsi que, sur le championnat europ\u00e9en 85cc, Thibault Benistant et David Braceras.<\/p>\n<h5>Thierry Van Den Bosch et David Vuillemin comme entra\u00eeneurs<\/h5>\n<p>\u00ab\u00a0La saison d\u00e9marre tr\u00e8s t\u00f4t pour nous cette ann\u00e9e avec le championnat US\u00a0\u00bb, explique St\u00e9phane Dasse. \u00ab\u00a0C&rsquo;est un nouveau challenge qui s&rsquo;annonce passionnant, nous serons \u00e0 100% derri\u00e8re eux afin d&rsquo;obtenir les meilleurs r\u00e9sultats possibles. Avec les programmes europ\u00e9ens et fran\u00e7ais ensuite, nous aurons beaucoup de pilotes \u00e0 suivre mais nous aimons notre sport et le challenge que ces programmes repr\u00e9sentent. Nous avons la chance de pouvoir compter sur le soutien de partenaires s\u00e9rieux, comme Kawasaki Europe, Kawasaki US ou Monster Energy qui nous ont confirm\u00e9 d\u00e8s septembre qu&rsquo;ils seraient \u00e0 nos c\u00f4t\u00e9s et cela nous a permis de mettre sur pieds ce programme tr\u00e8s charg\u00e9.\u00a0\u00bb<\/p>\n<p>\u00ab\u00a0Nous avons un staff technique tr\u00e8s professionnel et nous sommes heureux d&rsquo;accueillir \u00e0 pr\u00e9sent Thierry Van Den Bosch et David Vuillemin en tant qu&rsquo;entra\u00eeneurs. Nous les connaissons depuis longtemps et ils sont d\u00e9j\u00e0 occup\u00e9s \u00e0 travailler avec nos pilotes. C&rsquo;est en hiver qu&rsquo;une saison se construit ! La collaboration au sein du team semble excellente, nous sommes donc confiants, voire optimistes, pour la saison prochaine !\u00a0\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le team Kawasaki Bud Racing se pr\u00e9pare \u00e0 un programme 2016 pour le moins charg\u00e9. Pas moins de 7 pilotes porteront les couleurs du team fran\u00e7ais avec des programmes qui [&#8230;]<\/p>\n","protected":false},"author":932,"featured_media":33533,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[54,128,4,27,5,55,65],"tags":[],"class_list":["post-41227","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite","category-emx-125-emx2","category-motocross","category-sx-us","category-news","category-news-actualite","category-slideshow"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bud Racing sur tous les fronts - Motocross - Enduro - Supermoto | MotocrossMag<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fr.motocrossmag.be\/index.php\/2015\/12\/bud-racing-sur-tous-les-fronts\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bud Racing sur tous les fronts - Motocross - Enduro - Supermoto | MotocrossMag\" \/>\n<meta property=\"og:description\" content=\"Le team Kawasaki Bud Racing se pr\u00e9pare \u00e0 un programme 2016 pour le moins charg\u00e9. Pas moins de 7 pilotes porteront les couleurs du team fran\u00e7ais avec des programmes qui [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fr.motocrossmag.be\/index.php\/2015\/12\/bud-racing-sur-tous-les-fronts\/\" \/>\n<meta property=\"og:site_name\" content=\"Motocross - Enduro - Supermoto | MotocrossMag\" \/>\n<meta property=\"article:published_time\" content=\"2015-12-10T14:18:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-12-10T14:33:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2015\/05\/Xavier-Boog.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"675\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"oliviere\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"oliviere\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2015\\\/12\\\/bud-racing-sur-tous-les-fronts\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2015\\\/12\\\/bud-racing-sur-tous-les-fronts\\\/\"},\"author\":{\"name\":\"oliviere\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#\\\/schema\\\/person\\\/11b47143d9f755babca2c9110e03235c\"},\"headline\":\"Bud Racing sur tous les fronts\",\"datePublished\":\"2015-12-10T14:18:35+00:00\",\"dateModified\":\"2015-12-10T14:33:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2015\\\/12\\\/bud-racing-sur-tous-les-fronts\\\/\"},\"wordCount\":394,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2015\\\/12\\\/bud-racing-sur-tous-les-fronts\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fr.motocrossmag.be\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/Xavier-Boog.jpg\",\"articleSection\":[\"Actualit\u00e9\",\"EMX\",\"Motocross\",\"MX\\\/SX US\",\"News\",\"News\",\"Slideshow\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2015\\\/12\\\/bud-racing-sur-tous-les-fronts\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2015\\\/12\\\/bud-racing-sur-tous-les-fronts\\\/\",\"url\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2015\\\/12\\\/bud-racing-sur-tous-les-fronts\\\/\",\"name\":\"Bud Racing sur tous les fronts - Motocross - Enduro - Supermoto | MotocrossMag\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2015\\\/12\\\/bud-racing-sur-tous-les-fronts\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2015\\\/12\\\/bud-racing-sur-tous-les-fronts\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fr.motocrossmag.be\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/Xavier-Boog.jpg\",\"datePublished\":\"2015-12-10T14:18:35+00:00\",\"dateModified\":\"2015-12-10T14:33:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#\\\/schema\\\/person\\\/11b47143d9f755babca2c9110e03235c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2015\\\/12\\\/bud-racing-sur-tous-les-fronts\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2015\\\/12\\\/bud-racing-sur-tous-les-fronts\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2015\\\/12\\\/bud-racing-sur-tous-les-fronts\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fr.motocrossmag.be\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/Xavier-Boog.jpg\",\"contentUrl\":\"https:\\\/\\\/fr.motocrossmag.be\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/Xavier-Boog.jpg\",\"width\":675,\"height\":450,\"caption\":\"Xavier Boog: il retrouve le top-dix avec plaisir\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2015\\\/12\\\/bud-racing-sur-tous-les-fronts\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/fr.motocrossmag.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bud Racing sur tous les fronts\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#website\",\"url\":\"https:\\\/\\\/fr.motocrossmag.be\\\/\",\"name\":\"Motocross - Enduro - Supermoto | MotocrossMag\",\"description\":\"L&#039;actualit\u00e9 du motocross, de l&#039;enduro et du Supermoto en ligne!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fr.motocrossmag.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#\\\/schema\\\/person\\\/11b47143d9f755babca2c9110e03235c\",\"name\":\"oliviere\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g\",\"caption\":\"oliviere\"},\"sameAs\":[\"http:\\\/\\\/www.motocrossmag.be\"],\"url\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/author\\\/oliviere\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bud Racing sur tous les fronts - Motocross - Enduro - Supermoto | MotocrossMag","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fr.motocrossmag.be\/index.php\/2015\/12\/bud-racing-sur-tous-les-fronts\/","og_locale":"fr_FR","og_type":"article","og_title":"Bud Racing sur tous les fronts - Motocross - Enduro - Supermoto | MotocrossMag","og_description":"Le team Kawasaki Bud Racing se pr\u00e9pare \u00e0 un programme 2016 pour le moins charg\u00e9. Pas moins de 7 pilotes porteront les couleurs du team fran\u00e7ais avec des programmes qui [...]","og_url":"https:\/\/fr.motocrossmag.be\/index.php\/2015\/12\/bud-racing-sur-tous-les-fronts\/","og_site_name":"Motocross - Enduro - Supermoto | MotocrossMag","article_published_time":"2015-12-10T14:18:35+00:00","article_modified_time":"2015-12-10T14:33:35+00:00","og_image":[{"width":675,"height":450,"url":"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2015\/05\/Xavier-Boog.jpg","type":"image\/jpeg"}],"author":"oliviere","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"oliviere","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fr.motocrossmag.be\/index.php\/2015\/12\/bud-racing-sur-tous-les-fronts\/#article","isPartOf":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2015\/12\/bud-racing-sur-tous-les-fronts\/"},"author":{"name":"oliviere","@id":"https:\/\/fr.motocrossmag.be\/#\/schema\/person\/11b47143d9f755babca2c9110e03235c"},"headline":"Bud Racing sur tous les fronts","datePublished":"2015-12-10T14:18:35+00:00","dateModified":"2015-12-10T14:33:35+00:00","mainEntityOfPage":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2015\/12\/bud-racing-sur-tous-les-fronts\/"},"wordCount":394,"commentCount":0,"image":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2015\/12\/bud-racing-sur-tous-les-fronts\/#primaryimage"},"thumbnailUrl":"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2015\/05\/Xavier-Boog.jpg","articleSection":["Actualit\u00e9","EMX","Motocross","MX\/SX US","News","News","Slideshow"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fr.motocrossmag.be\/index.php\/2015\/12\/bud-racing-sur-tous-les-fronts\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fr.motocrossmag.be\/index.php\/2015\/12\/bud-racing-sur-tous-les-fronts\/","url":"https:\/\/fr.motocrossmag.be\/index.php\/2015\/12\/bud-racing-sur-tous-les-fronts\/","name":"Bud Racing sur tous les fronts - Motocross - Enduro - Supermoto | MotocrossMag","isPartOf":{"@id":"https:\/\/fr.motocrossmag.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2015\/12\/bud-racing-sur-tous-les-fronts\/#primaryimage"},"image":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2015\/12\/bud-racing-sur-tous-les-fronts\/#primaryimage"},"thumbnailUrl":"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2015\/05\/Xavier-Boog.jpg","datePublished":"2015-12-10T14:18:35+00:00","dateModified":"2015-12-10T14:33:35+00:00","author":{"@id":"https:\/\/fr.motocrossmag.be\/#\/schema\/person\/11b47143d9f755babca2c9110e03235c"},"breadcrumb":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2015\/12\/bud-racing-sur-tous-les-fronts\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fr.motocrossmag.be\/index.php\/2015\/12\/bud-racing-sur-tous-les-fronts\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/fr.motocrossmag.be\/index.php\/2015\/12\/bud-racing-sur-tous-les-fronts\/#primaryimage","url":"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2015\/05\/Xavier-Boog.jpg","contentUrl":"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2015\/05\/Xavier-Boog.jpg","width":675,"height":450,"caption":"Xavier Boog: il retrouve le top-dix avec plaisir"},{"@type":"BreadcrumbList","@id":"https:\/\/fr.motocrossmag.be\/index.php\/2015\/12\/bud-racing-sur-tous-les-fronts\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/fr.motocrossmag.be\/"},{"@type":"ListItem","position":2,"name":"Bud Racing sur tous les fronts"}]},{"@type":"WebSite","@id":"https:\/\/fr.motocrossmag.be\/#website","url":"https:\/\/fr.motocrossmag.be\/","name":"Motocross - Enduro - Supermoto | MotocrossMag","description":"L&#039;actualit\u00e9 du motocross, de l&#039;enduro et du Supermoto en ligne!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fr.motocrossmag.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/fr.motocrossmag.be\/#\/schema\/person\/11b47143d9f755babca2c9110e03235c","name":"oliviere","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g","caption":"oliviere"},"sameAs":["http:\/\/www.motocrossmag.be"],"url":"https:\/\/fr.motocrossmag.be\/index.php\/author\/oliviere\/"}]}},"_links":{"self":[{"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/posts\/41227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/users\/932"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/comments?post=41227"}],"version-history":[{"count":2,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/posts\/41227\/revisions"}],"predecessor-version":[{"id":41229,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/posts\/41227\/revisions\/41229"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/media\/33533"}],"wp:attachment":[{"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/media?parent=41227"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/categories?post=41227"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/tags?post=41227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}