{"id":64732,"date":"2017-09-14T21:14:28","date_gmt":"2017-09-14T19:14:28","guid":{"rendered":"http:\/\/fr.motocrossmag.be\/?p=64732"},"modified":"2017-09-14T21:14:28","modified_gmt":"2017-09-14T19:14:28","slug":"erik-willems-de-lambition-a-revendre","status":"publish","type":"post","link":"https:\/\/fr.motocrossmag.be\/index.php\/2017\/09\/erik-willems-de-lambition-a-revendre\/","title":{"rendered":"Erik Willems : de l&rsquo;ambition \u00e0 revendre !"},"content":{"rendered":"<p><strong>S&rsquo;il est une date inscrite en rouge dans l&rsquo;agenda d&rsquo;Erik Willems, c&rsquo;est assur\u00e9ment celle du 8 octobre prochain. Le jeune pilote Husqvarna, 19 ans, disputera en effet le deuxi\u00e8me week-end d&rsquo;octobre la finale du championnat de Belgique de motocross sur le circuit de Baisieux. Apr\u00e8s une saison europ\u00e9enne prometteuse, le Braban\u00e7on tentera d&rsquo;inscrire un titre de champion de Belgique \u00e0 son palmar\u00e8s.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Tu arriveras \u00e0 Baisieux avec 11 points de retard sur Dietger Damiaens. Tu as donc encore une chance de devenir champion de Belgique. Quoi qu&rsquo;il arrive, tu as assur\u00e9ment donn\u00e9 de la couleur au championnat !<\/strong><\/p>\n<p>Erik Willems : \u00ab\u00a0Oui, en effet, nous nous battons depuis le d\u00e9but de saison et cela rend le championnat int\u00e9ressant. Dietger et moi sommes du m\u00eame niveau. Dommage que j&rsquo;ai connu des ennuis m\u00e9caniques, mais ce sont des choses qui arrivent. En fait, apr\u00e8s Orp-le-Grand, j&rsquo;\u00e9tais en plein dilemme car Robert Gielis m&rsquo;avait s\u00e9lectionn\u00e9 pour la Coupe de l&rsquo;Avenir afin de rouler dans le team belge. Mais comme l&rsquo;\u00e9preuve a lieu en m\u00eame temps que la finale du championnat, j&rsquo;ai d\u00fb faire un choix. J&rsquo;ai pr\u00e9f\u00e9r\u00e9 disputer le championnat jusqu&rsquo;au bout. On verra bien comment cela se termine !\u00a0\u00bb<\/p>\n<p><strong>Un commentaire sur les bons r\u00e9sultats obtenus cette saison ?<\/strong><\/p>\n<p>Erik Willems : \u00ab\u00a0L&rsquo;hiver pass\u00e9, je n&rsquo;ai pas trop travaill\u00e9. Je me suis plut\u00f4t concentr\u00e9 sur le fait d&rsquo;arriver en forme pour la premi\u00e8re \u00e9preuve du championnat EMX300, qui se d\u00e9roulait le 21 mai seulement en Allemagne. Dans les premi\u00e8res \u00e9preuves FMB de la saison, je voulais surtout prendre de bons d\u00e9parts, rester calme, ne pas chuter et marquer de gros points. Je n&rsquo;avais certainement pas l&rsquo;ambition de gagner. J&rsquo;avais bien s\u00fbr l&rsquo;envie de bien figurer au championnat mais un championnat comme celui-l\u00e0, il n&rsquo;y a pas vraiment d&rsquo;autre possibilit\u00e9 que de le prendre course apr\u00e8s course. Et cette strat\u00e9gie m&rsquo;a plut\u00f4t bien r\u00e9ussi !\u00a0\u00bb<\/p>\n<p><img decoding=\"async\" class=\"lazyload alignnone size-medium wp-image-64740\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27650%27%20height%3D%27433%27%20viewBox%3D%270%200%20650%20433%27%3E%3Crect%20width%3D%27650%27%20height%3D%27433%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2017\/09\/erik-willems-grid-650x433.jpg\" alt=\"\" width=\"650\" height=\"433\" \/><\/p>\n<p><strong>Qu&rsquo;avais-tu fait l&rsquo;an dernier ?<\/strong><\/p>\n<p>Erik Willems : \u00ab\u00a0J&rsquo;ai fait beaucoup de cross inters en France, quelques courses en Hollande et en Belgique, notamment \u00e0 Orp et Balen, aussi. En France, j&rsquo;ai roul\u00e9 dans le top-10 sur les \u00e9preuves Elite de Romagn\u00e9 et Saint-Thibery. A Markelo, j&rsquo;ai aussi termin\u00e9 dans le top-10 avec une Yamaha 450. Mon objectif, c&rsquo;est d&rsquo;arriver en GP d&rsquo;ici 2 \u00e0 3 ans et je sais combien il est important de savoir rouler sur tous les types de circuits.\u00a0\u00bb<\/p>\n<p><strong>Tu travailles avec un entra\u00eeneur ?<\/strong><\/p>\n<p>Erik Willems : \u00ab\u00a0Non, je n&rsquo;ai pas d&rsquo;entra\u00eeneur personnel. Mais je contacte r\u00e9guli\u00e8rement Yves Devlaminck. J&rsquo;ai aussi fait un stage avec Jeremy Coen. J&rsquo;ai par contre un coach physique, Mathieu Beulens, qui entra\u00eene aussi Jeremy Coen. Il m&rsquo;a concoct\u00e9 un programme. A c\u00f4t\u00e9 de cela, j&rsquo;essaie aussi d&rsquo;\u00e9changer avec de bons pilotes ou alors d&rsquo;alle rouler avec eux, comme Nicolas Dercourt. J&rsquo;ai m\u00eame d\u00e9j\u00e0 roul\u00e9 avec Jeffrey Herlings. Je roule souvent dans le nord de la France.\u00a0\u00bb<\/p>\n<p><strong>As-tu l&rsquo;impression d&rsquo;avoir davantage de supporters parce que tu roules sur une machine 2-temps ?<\/strong><\/p>\n<p>Erik Willems : \u00ab\u00a0Oui ! Ce n&rsquo;est pas toujours simple mais j&rsquo;aime le pilotage du 2-temps. A l&rsquo;invitation de Stefaan Minne, de Husqvarna Belgique, je suis all\u00e9 sur la pr\u00e9sentation des Husqvarna 2018 \u00e0 Veldhoven. L\u00e0, j&rsquo;ai pu tester toute la gamme. Bien s\u00fbr, je suis un peu plus rapide avec une 450 mais je prends malgr\u00e9 tout plus de plaisir sur la 2-temps ! Je suis tr\u00e8s content du feeling que j&rsquo;ai avec la Husqvarna. Avec Ronny Van Hove, nous avons bien travaill\u00e9 sur les r\u00e9glages de la moto. Ma prochaine course, ce sera la finale du championnat EMX250 \u00e0 Villars-sous-Ecot, en France, ce week-end. J&rsquo;y roulerai avec une 250 2-temps. Sans doute serai-je le seul 2-temps au d\u00e9part ! Bon, on verra comment cela se passe&#8230; mon premier objectif, c&rsquo;est \u00e9videmment de me qualifier.\u00a0\u00bb<\/p>\n<p><img decoding=\"async\" class=\"lazyload alignnone size-medium wp-image-58302\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27650%27%20height%3D%27433%27%20viewBox%3D%270%200%20650%20433%27%3E%3Crect%20width%3D%27650%27%20height%3D%27433%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"http:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2017\/04\/erik-willems-sable-650x433.jpg\" alt=\"\" width=\"650\" height=\"433\" \/><\/p>\n<p><strong>Un titre EMX300 parmi les prochains objectifs ?<\/strong><\/p>\n<p>Erik Willems : \u00ab\u00a0Oui, cela en fait en effet partie, remporter le titre EMX300 au guidon de la Husqvarna. A moins qu&rsquo;une autre offre plus int\u00e9ressante n&rsquo;arrive, \u00e9videmment. Sur le plan national, je ne sais pas encore bien. Je pourrais faire le championnat de Hollande au guidon d&rsquo;une 250 2-temps, ce qui sera autoris\u00e9 en 2018. Cela peut certainement \u00eatre int\u00e9ressant de rouler le championnat Dutch Masters face \u00e0 des pilotes comme Thomas Covington, Thomas Kjer Olsen, Bas Vaessen ou Calvin Vlaanderen.\u00a0\u00bb<\/p>\n<p><strong>A c\u00f4t\u00e9 du motocross, que fais-tu ?<\/strong><\/p>\n<p>Erik Willems : \u00ab\u00a0Je viens de terminer mes \u00e9tudes secondaires et je travaille \u00e0 pr\u00e9sent 2 jours par semaine dans l&rsquo;entreprise de mon p\u00e8re. Le reste du temps, je peux m&rsquo;entra\u00eener et me concentrer sur le motocross. J&rsquo;esp\u00e8re l&rsquo;an prochain recevoir davantage de soutien de la part de l&rsquo;ADEPS. Je veux \u00e9voluer \u00e9tape par \u00e9tape, en \u00e9vitant les blessures. Cette ann\u00e9e s&rsquo;est bien d\u00e9roul\u00e9e. Je sais que le chemin est encore long mais le travail est toujours r\u00e9compens\u00e9 !\u00a0\u00bb<strong><br \/>\n<\/strong><\/p>\n<p><strong>Sais-tu d\u00e9j\u00e0 ce que tu feras en 2019 ?<\/strong><\/p>\n<p>Erik Willems : \u00ab\u00a0Comme expliqu\u00e9, je voudrais id\u00e9alement pouvoir enlever le titre EMX300 l&rsquo;an prochain, ce qui me permettrait de me lancer en MXGP en 2019. Mon \u00e2ge joue en ma faveur, j&rsquo;ai sans doute encore une belle marge de progression. J&rsquo;ai tr\u00e8s envie d&rsquo;apprendre, de progresser chaque jour. Je sais que j&rsquo;aurai pour cela besoin d&rsquo;un coach, quelqu&rsquo;un qui me suive \u00e0 l&rsquo;entra\u00eenement, qui sait voir ce que je dois am\u00e9liorer. Mon p\u00e8re n&rsquo;a pas l&rsquo;exp\u00e9rience n\u00e9cessaire. Il a roul\u00e9 un peu en enduro mais il ne m&rsquo;a pas pouss\u00e9 \u00e0 faire du motocross pour accomplir un de ses r\u00eaves ou quelque chose du genre. C&rsquo;est peut-\u00eatre cela ma force. Il m&rsquo;a soutenu parce que je voulais rouler et que j&rsquo;ai toujours fait ce qu&rsquo;il fallait pour m&rsquo;am\u00e9liorer. D&rsquo;autres ne peuvent pas supporter la pression mise par leurs parents et finissent par arr\u00eater.\u00a0\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>S&rsquo;il est une date inscrite en rouge dans l&rsquo;agenda d&rsquo;Erik Willems, c&rsquo;est assur\u00e9ment celle du 8 octobre prochain. Le jeune pilote Husqvarna, 19 ans, disputera en effet le deuxi\u00e8me week-end [&#8230;]<\/p>\n","protected":false},"author":932,"featured_media":59799,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[54,128,7,58,4,29,5,55,65],"tags":[],"class_list":["post-64732","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite","category-emx-125-emx2","category-interviews","category-interviews-actualite","category-motocross","category-fmb","category-news","category-news-actualite","category-slideshow"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Erik Willems : de l&#039;ambition \u00e0 revendre ! - Motocross - Enduro - Supermoto | MotocrossMag<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fr.motocrossmag.be\/index.php\/2017\/09\/erik-willems-de-lambition-a-revendre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Erik Willems : de l&#039;ambition \u00e0 revendre ! - Motocross - Enduro - Supermoto | MotocrossMag\" \/>\n<meta property=\"og:description\" content=\"S&rsquo;il est une date inscrite en rouge dans l&rsquo;agenda d&rsquo;Erik Willems, c&rsquo;est assur\u00e9ment celle du 8 octobre prochain. Le jeune pilote Husqvarna, 19 ans, disputera en effet le deuxi\u00e8me week-end [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fr.motocrossmag.be\/index.php\/2017\/09\/erik-willems-de-lambition-a-revendre\/\" \/>\n<meta property=\"og:site_name\" content=\"Motocross - Enduro - Supermoto | MotocrossMag\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-14T19:14:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2017\/05\/teutschenthal-willems-erik.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"877\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"oliviere\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"oliviere\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2017\\\/09\\\/erik-willems-de-lambition-a-revendre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2017\\\/09\\\/erik-willems-de-lambition-a-revendre\\\/\"},\"author\":{\"name\":\"oliviere\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#\\\/schema\\\/person\\\/11b47143d9f755babca2c9110e03235c\"},\"headline\":\"Erik Willems : de l&rsquo;ambition \u00e0 revendre !\",\"datePublished\":\"2017-09-14T19:14:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2017\\\/09\\\/erik-willems-de-lambition-a-revendre\\\/\"},\"wordCount\":1058,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2017\\\/09\\\/erik-willems-de-lambition-a-revendre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fr.motocrossmag.be\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/teutschenthal-willems-erik.jpg\",\"articleSection\":[\"Actualit\u00e9\",\"EMX\",\"Interviews\",\"Interviews -all\",\"Motocross\",\"Motocross FMB\",\"News\",\"News\",\"Slideshow\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2017\\\/09\\\/erik-willems-de-lambition-a-revendre\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2017\\\/09\\\/erik-willems-de-lambition-a-revendre\\\/\",\"url\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2017\\\/09\\\/erik-willems-de-lambition-a-revendre\\\/\",\"name\":\"Erik Willems : de l'ambition \u00e0 revendre ! - Motocross - Enduro - Supermoto | MotocrossMag\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2017\\\/09\\\/erik-willems-de-lambition-a-revendre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2017\\\/09\\\/erik-willems-de-lambition-a-revendre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fr.motocrossmag.be\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/teutschenthal-willems-erik.jpg\",\"datePublished\":\"2017-09-14T19:14:28+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#\\\/schema\\\/person\\\/11b47143d9f755babca2c9110e03235c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2017\\\/09\\\/erik-willems-de-lambition-a-revendre\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2017\\\/09\\\/erik-willems-de-lambition-a-revendre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2017\\\/09\\\/erik-willems-de-lambition-a-revendre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fr.motocrossmag.be\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/teutschenthal-willems-erik.jpg\",\"contentUrl\":\"https:\\\/\\\/fr.motocrossmag.be\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/teutschenthal-willems-erik.jpg\",\"width\":1400,\"height\":877},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2017\\\/09\\\/erik-willems-de-lambition-a-revendre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/fr.motocrossmag.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Erik Willems : de l&rsquo;ambition \u00e0 revendre !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#website\",\"url\":\"https:\\\/\\\/fr.motocrossmag.be\\\/\",\"name\":\"Motocross - Enduro - Supermoto | MotocrossMag\",\"description\":\"L&#039;actualit\u00e9 du motocross, de l&#039;enduro et du Supermoto en ligne!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fr.motocrossmag.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#\\\/schema\\\/person\\\/11b47143d9f755babca2c9110e03235c\",\"name\":\"oliviere\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g\",\"caption\":\"oliviere\"},\"sameAs\":[\"http:\\\/\\\/www.motocrossmag.be\"],\"url\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/author\\\/oliviere\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Erik Willems : de l'ambition \u00e0 revendre ! - Motocross - Enduro - Supermoto | MotocrossMag","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fr.motocrossmag.be\/index.php\/2017\/09\/erik-willems-de-lambition-a-revendre\/","og_locale":"fr_FR","og_type":"article","og_title":"Erik Willems : de l'ambition \u00e0 revendre ! - Motocross - Enduro - Supermoto | MotocrossMag","og_description":"S&rsquo;il est une date inscrite en rouge dans l&rsquo;agenda d&rsquo;Erik Willems, c&rsquo;est assur\u00e9ment celle du 8 octobre prochain. Le jeune pilote Husqvarna, 19 ans, disputera en effet le deuxi\u00e8me week-end [...]","og_url":"https:\/\/fr.motocrossmag.be\/index.php\/2017\/09\/erik-willems-de-lambition-a-revendre\/","og_site_name":"Motocross - Enduro - Supermoto | MotocrossMag","article_published_time":"2017-09-14T19:14:28+00:00","og_image":[{"width":1400,"height":877,"url":"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2017\/05\/teutschenthal-willems-erik.jpg","type":"image\/jpeg"}],"author":"oliviere","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"oliviere","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fr.motocrossmag.be\/index.php\/2017\/09\/erik-willems-de-lambition-a-revendre\/#article","isPartOf":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2017\/09\/erik-willems-de-lambition-a-revendre\/"},"author":{"name":"oliviere","@id":"https:\/\/fr.motocrossmag.be\/#\/schema\/person\/11b47143d9f755babca2c9110e03235c"},"headline":"Erik Willems : de l&rsquo;ambition \u00e0 revendre !","datePublished":"2017-09-14T19:14:28+00:00","mainEntityOfPage":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2017\/09\/erik-willems-de-lambition-a-revendre\/"},"wordCount":1058,"commentCount":0,"image":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2017\/09\/erik-willems-de-lambition-a-revendre\/#primaryimage"},"thumbnailUrl":"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2017\/05\/teutschenthal-willems-erik.jpg","articleSection":["Actualit\u00e9","EMX","Interviews","Interviews -all","Motocross","Motocross FMB","News","News","Slideshow"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fr.motocrossmag.be\/index.php\/2017\/09\/erik-willems-de-lambition-a-revendre\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fr.motocrossmag.be\/index.php\/2017\/09\/erik-willems-de-lambition-a-revendre\/","url":"https:\/\/fr.motocrossmag.be\/index.php\/2017\/09\/erik-willems-de-lambition-a-revendre\/","name":"Erik Willems : de l'ambition \u00e0 revendre ! - Motocross - Enduro - Supermoto | MotocrossMag","isPartOf":{"@id":"https:\/\/fr.motocrossmag.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2017\/09\/erik-willems-de-lambition-a-revendre\/#primaryimage"},"image":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2017\/09\/erik-willems-de-lambition-a-revendre\/#primaryimage"},"thumbnailUrl":"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2017\/05\/teutschenthal-willems-erik.jpg","datePublished":"2017-09-14T19:14:28+00:00","author":{"@id":"https:\/\/fr.motocrossmag.be\/#\/schema\/person\/11b47143d9f755babca2c9110e03235c"},"breadcrumb":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2017\/09\/erik-willems-de-lambition-a-revendre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fr.motocrossmag.be\/index.php\/2017\/09\/erik-willems-de-lambition-a-revendre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/fr.motocrossmag.be\/index.php\/2017\/09\/erik-willems-de-lambition-a-revendre\/#primaryimage","url":"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2017\/05\/teutschenthal-willems-erik.jpg","contentUrl":"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2017\/05\/teutschenthal-willems-erik.jpg","width":1400,"height":877},{"@type":"BreadcrumbList","@id":"https:\/\/fr.motocrossmag.be\/index.php\/2017\/09\/erik-willems-de-lambition-a-revendre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/fr.motocrossmag.be\/"},{"@type":"ListItem","position":2,"name":"Erik Willems : de l&rsquo;ambition \u00e0 revendre !"}]},{"@type":"WebSite","@id":"https:\/\/fr.motocrossmag.be\/#website","url":"https:\/\/fr.motocrossmag.be\/","name":"Motocross - Enduro - Supermoto | MotocrossMag","description":"L&#039;actualit\u00e9 du motocross, de l&#039;enduro et du Supermoto en ligne!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fr.motocrossmag.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/fr.motocrossmag.be\/#\/schema\/person\/11b47143d9f755babca2c9110e03235c","name":"oliviere","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g","caption":"oliviere"},"sameAs":["http:\/\/www.motocrossmag.be"],"url":"https:\/\/fr.motocrossmag.be\/index.php\/author\/oliviere\/"}]}},"_links":{"self":[{"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/posts\/64732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/users\/932"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/comments?post=64732"}],"version-history":[{"count":2,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/posts\/64732\/revisions"}],"predecessor-version":[{"id":64741,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/posts\/64732\/revisions\/64741"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/media\/59799"}],"wp:attachment":[{"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/media?parent=64732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/categories?post=64732"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/tags?post=64732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}