{"id":77765,"date":"2018-08-10T12:35:49","date_gmt":"2018-08-10T10:35:49","guid":{"rendered":"http:\/\/fr.motocrossmag.be\/?p=77765"},"modified":"2018-08-10T12:36:18","modified_gmt":"2018-08-10T10:36:18","slug":"les-12-heures-de-la-chinelle-le-programme-du-week-end","status":"publish","type":"post","link":"https:\/\/fr.motocrossmag.be\/index.php\/2018\/08\/les-12-heures-de-la-chinelle-le-programme-du-week-end\/","title":{"rendered":"Les 12 Heures de la Chinelle : le programme du week-end"},"content":{"rendered":"<p>Le d\u00e9part de la 39\u00e8me \u00e9dition des 12 Heures de la Chinelle se donnera ce samedi 11 ao\u00fbt \u00e0 minuit pr\u00e9cise. Mais le spectacle d\u00e9butera bien avant \u00e0 Franchimont. D\u00e8s ce vendredi apr\u00e8s-midi, les participants seront pr\u00e9sent\u00e9s sur la place de Philippeville avant de rejoindre en cort\u00e8ge le site des 12 Heures. Samedi, la Mini-Chinelle ouvrira le bal avant les courses r\u00e9serv\u00e9es aux machines d&rsquo;\u00e9poque tandis que les premiers essais pour les pilotes engag\u00e9s dans les 12 Heures d\u00e9buteront \u00e0 15h45. D\u00e8s 23h30, les machines seront plac\u00e9es une \u00e0 une sur la ligne droite des stands avant le d\u00e9compte final jusqu&rsquo;aux douze coups de minuit qui marqueront le lancement du tour d&rsquo;horloge pour la centaine d&rsquo;\u00e9quipages engag\u00e9s. Arriv\u00e9e le dimanche \u00e0 midi.<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\"><strong>Programme Chinelle 2018<\/strong><\/span><\/p>\n<h5>Vendredi 10 ao\u00fbt 2018<\/h5>\n<p>09h00 \u2013 20h00 :\u00a0Accueil des participants au secr\u00e9tariat, place de SURICE<br \/>\n09h00 \u2013 20h00 :\u00a0Accueil des participants aux 2 heures R.M.T. au secr\u00e9tariat, place de SURICE<br \/>\n15h00 \u2013 18h00 :\u00a0Contr\u00f4le technique, place de PHILIPPEVILLE<br \/>\n15h30 :\u00a0Pr\u00e9sentation des \u00e9quipages sur la place de PHILIPPEVILLE<br \/>\n18h30 :\u00a0Parade des \u00e9quipages vers la Chinelle<br \/>\n18h00 \u2013 21h00 :\u00a0Contr\u00f4le technique anc\u00eatres, chapiteau historique<br \/>\n21h00 :\u00a0Fermeture de l\u2019acc\u00e8s aux stands<\/p>\n<h5>Samedi 11 ao\u00fbt 2018<\/h5>\n<p>7h \u2013 9h45\u00a0: Cont\u00f4le administratif SURICE<br \/>\n7h \u2013 8h\u00a0: Contr\u00f4le technique Mini Chinelle<br \/>\n8h \u2013 9h\u00a0: Contr\u00f4le technique Anc\u00eatres<br \/>\n8h30 \u2013 9h15\u00a0: Essais Mini Chinelle (45 min)<br \/>\n9h30 \u2013 11h\u00a0: Essais Vintage &amp; Evo (1h30)<br \/>\n11h15 \u2013 13h15\u00a0: Course 2h Mini Chinelle<br \/>\n13h30 \u2013 15h30\u00a0: Course 2h Vintage<br \/>\n15h45 \u2013 16h45\u00a0: Essai 12 H<br \/>\n16 h\u00a0: Remise des prix Mini Chinelle<br \/>\n17h \u2013 19h\u00a0: Course 2 H Evolution<br \/>\n19h30\u00a0: Remise des prix Vintage &amp; Evolution<br \/>\n20h \u2013 23h\u00a0: Essais 12 H<br \/>\n20h30 \u2013 21h30\u00a0: Essais Chrono 12 H<br \/>\n23h30\u00a0: Mise en grille d\u00e9part 12 H<br \/>\n23h50\u00a0: Fermeture sortie des stands<br \/>\n00h00 : D\u00e9part des 12h de la Chinelle<\/p>\n<h5>Dimanche 12 ao\u00fbt 2018<\/h5>\n<p>00h00 :\u00a0D\u00e9part de la course des 12 heures<br \/>\n12h00 :\u00a0Arriv\u00e9e de la course<br \/>\n12h15 :\u00a0Podium et remise des prix de la Chinelle<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le d\u00e9part de la 39\u00e8me \u00e9dition des 12 Heures de la Chinelle se donnera ce samedi 11 ao\u00fbt \u00e0 minuit pr\u00e9cise. Mais le spectacle d\u00e9butera bien avant \u00e0 Franchimont. D\u00e8s [&#8230;]<\/p>\n","protected":false},"author":932,"featured_media":12590,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[54,73,55,65],"tags":[],"class_list":["post-77765","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite","category-chinelle","category-news-actualite","category-slideshow"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les 12 Heures de la Chinelle : le programme du week-end - Motocross - Enduro - Supermoto | MotocrossMag<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fr.motocrossmag.be\/index.php\/2018\/08\/les-12-heures-de-la-chinelle-le-programme-du-week-end\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les 12 Heures de la Chinelle : le programme du week-end - Motocross - Enduro - Supermoto | MotocrossMag\" \/>\n<meta property=\"og:description\" content=\"Le d\u00e9part de la 39\u00e8me \u00e9dition des 12 Heures de la Chinelle se donnera ce samedi 11 ao\u00fbt \u00e0 minuit pr\u00e9cise. Mais le spectacle d\u00e9butera bien avant \u00e0 Franchimont. D\u00e8s [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fr.motocrossmag.be\/index.php\/2018\/08\/les-12-heures-de-la-chinelle-le-programme-du-week-end\/\" \/>\n<meta property=\"og:site_name\" content=\"Motocross - Enduro - Supermoto | MotocrossMag\" \/>\n<meta property=\"article:published_time\" content=\"2018-08-10T10:35:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-08-10T10:36:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2011\/08\/chinelle_24.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"oliviere\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"oliviere\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2018\\\/08\\\/les-12-heures-de-la-chinelle-le-programme-du-week-end\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2018\\\/08\\\/les-12-heures-de-la-chinelle-le-programme-du-week-end\\\/\"},\"author\":{\"name\":\"oliviere\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#\\\/schema\\\/person\\\/11b47143d9f755babca2c9110e03235c\"},\"headline\":\"Les 12 Heures de la Chinelle : le programme du week-end\",\"datePublished\":\"2018-08-10T10:35:49+00:00\",\"dateModified\":\"2018-08-10T10:36:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2018\\\/08\\\/les-12-heures-de-la-chinelle-le-programme-du-week-end\\\/\"},\"wordCount\":343,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2018\\\/08\\\/les-12-heures-de-la-chinelle-le-programme-du-week-end\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fr.motocrossmag.be\\\/wp-content\\\/uploads\\\/2011\\\/08\\\/chinelle_24.jpg\",\"articleSection\":[\"Actualit\u00e9\",\"La Chinelle\",\"News\",\"Slideshow\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2018\\\/08\\\/les-12-heures-de-la-chinelle-le-programme-du-week-end\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2018\\\/08\\\/les-12-heures-de-la-chinelle-le-programme-du-week-end\\\/\",\"url\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2018\\\/08\\\/les-12-heures-de-la-chinelle-le-programme-du-week-end\\\/\",\"name\":\"Les 12 Heures de la Chinelle : le programme du week-end - Motocross - Enduro - Supermoto | MotocrossMag\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2018\\\/08\\\/les-12-heures-de-la-chinelle-le-programme-du-week-end\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2018\\\/08\\\/les-12-heures-de-la-chinelle-le-programme-du-week-end\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fr.motocrossmag.be\\\/wp-content\\\/uploads\\\/2011\\\/08\\\/chinelle_24.jpg\",\"datePublished\":\"2018-08-10T10:35:49+00:00\",\"dateModified\":\"2018-08-10T10:36:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#\\\/schema\\\/person\\\/11b47143d9f755babca2c9110e03235c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2018\\\/08\\\/les-12-heures-de-la-chinelle-le-programme-du-week-end\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2018\\\/08\\\/les-12-heures-de-la-chinelle-le-programme-du-week-end\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2018\\\/08\\\/les-12-heures-de-la-chinelle-le-programme-du-week-end\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fr.motocrossmag.be\\\/wp-content\\\/uploads\\\/2011\\\/08\\\/chinelle_24.jpg\",\"contentUrl\":\"https:\\\/\\\/fr.motocrossmag.be\\\/wp-content\\\/uploads\\\/2011\\\/08\\\/chinelle_24.jpg\",\"width\":900,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/2018\\\/08\\\/les-12-heures-de-la-chinelle-le-programme-du-week-end\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/fr.motocrossmag.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les 12 Heures de la Chinelle : le programme du week-end\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#website\",\"url\":\"https:\\\/\\\/fr.motocrossmag.be\\\/\",\"name\":\"Motocross - Enduro - Supermoto | MotocrossMag\",\"description\":\"L&#039;actualit\u00e9 du motocross, de l&#039;enduro et du Supermoto en ligne!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fr.motocrossmag.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fr.motocrossmag.be\\\/#\\\/schema\\\/person\\\/11b47143d9f755babca2c9110e03235c\",\"name\":\"oliviere\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g\",\"caption\":\"oliviere\"},\"sameAs\":[\"http:\\\/\\\/www.motocrossmag.be\"],\"url\":\"https:\\\/\\\/fr.motocrossmag.be\\\/index.php\\\/author\\\/oliviere\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les 12 Heures de la Chinelle : le programme du week-end - Motocross - Enduro - Supermoto | MotocrossMag","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fr.motocrossmag.be\/index.php\/2018\/08\/les-12-heures-de-la-chinelle-le-programme-du-week-end\/","og_locale":"fr_FR","og_type":"article","og_title":"Les 12 Heures de la Chinelle : le programme du week-end - Motocross - Enduro - Supermoto | MotocrossMag","og_description":"Le d\u00e9part de la 39\u00e8me \u00e9dition des 12 Heures de la Chinelle se donnera ce samedi 11 ao\u00fbt \u00e0 minuit pr\u00e9cise. Mais le spectacle d\u00e9butera bien avant \u00e0 Franchimont. D\u00e8s [...]","og_url":"https:\/\/fr.motocrossmag.be\/index.php\/2018\/08\/les-12-heures-de-la-chinelle-le-programme-du-week-end\/","og_site_name":"Motocross - Enduro - Supermoto | MotocrossMag","article_published_time":"2018-08-10T10:35:49+00:00","article_modified_time":"2018-08-10T10:36:18+00:00","og_image":[{"width":900,"height":600,"url":"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2011\/08\/chinelle_24.jpg","type":"image\/jpeg"}],"author":"oliviere","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"oliviere","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fr.motocrossmag.be\/index.php\/2018\/08\/les-12-heures-de-la-chinelle-le-programme-du-week-end\/#article","isPartOf":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2018\/08\/les-12-heures-de-la-chinelle-le-programme-du-week-end\/"},"author":{"name":"oliviere","@id":"https:\/\/fr.motocrossmag.be\/#\/schema\/person\/11b47143d9f755babca2c9110e03235c"},"headline":"Les 12 Heures de la Chinelle : le programme du week-end","datePublished":"2018-08-10T10:35:49+00:00","dateModified":"2018-08-10T10:36:18+00:00","mainEntityOfPage":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2018\/08\/les-12-heures-de-la-chinelle-le-programme-du-week-end\/"},"wordCount":343,"commentCount":0,"image":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2018\/08\/les-12-heures-de-la-chinelle-le-programme-du-week-end\/#primaryimage"},"thumbnailUrl":"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2011\/08\/chinelle_24.jpg","articleSection":["Actualit\u00e9","La Chinelle","News","Slideshow"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fr.motocrossmag.be\/index.php\/2018\/08\/les-12-heures-de-la-chinelle-le-programme-du-week-end\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fr.motocrossmag.be\/index.php\/2018\/08\/les-12-heures-de-la-chinelle-le-programme-du-week-end\/","url":"https:\/\/fr.motocrossmag.be\/index.php\/2018\/08\/les-12-heures-de-la-chinelle-le-programme-du-week-end\/","name":"Les 12 Heures de la Chinelle : le programme du week-end - Motocross - Enduro - Supermoto | MotocrossMag","isPartOf":{"@id":"https:\/\/fr.motocrossmag.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2018\/08\/les-12-heures-de-la-chinelle-le-programme-du-week-end\/#primaryimage"},"image":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2018\/08\/les-12-heures-de-la-chinelle-le-programme-du-week-end\/#primaryimage"},"thumbnailUrl":"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2011\/08\/chinelle_24.jpg","datePublished":"2018-08-10T10:35:49+00:00","dateModified":"2018-08-10T10:36:18+00:00","author":{"@id":"https:\/\/fr.motocrossmag.be\/#\/schema\/person\/11b47143d9f755babca2c9110e03235c"},"breadcrumb":{"@id":"https:\/\/fr.motocrossmag.be\/index.php\/2018\/08\/les-12-heures-de-la-chinelle-le-programme-du-week-end\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fr.motocrossmag.be\/index.php\/2018\/08\/les-12-heures-de-la-chinelle-le-programme-du-week-end\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/fr.motocrossmag.be\/index.php\/2018\/08\/les-12-heures-de-la-chinelle-le-programme-du-week-end\/#primaryimage","url":"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2011\/08\/chinelle_24.jpg","contentUrl":"https:\/\/fr.motocrossmag.be\/wp-content\/uploads\/2011\/08\/chinelle_24.jpg","width":900,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/fr.motocrossmag.be\/index.php\/2018\/08\/les-12-heures-de-la-chinelle-le-programme-du-week-end\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/fr.motocrossmag.be\/"},{"@type":"ListItem","position":2,"name":"Les 12 Heures de la Chinelle : le programme du week-end"}]},{"@type":"WebSite","@id":"https:\/\/fr.motocrossmag.be\/#website","url":"https:\/\/fr.motocrossmag.be\/","name":"Motocross - Enduro - Supermoto | MotocrossMag","description":"L&#039;actualit\u00e9 du motocross, de l&#039;enduro et du Supermoto en ligne!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fr.motocrossmag.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/fr.motocrossmag.be\/#\/schema\/person\/11b47143d9f755babca2c9110e03235c","name":"oliviere","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/907069e0b81d119452040469e4a7501da1100f54f7f80180ce77bfab718288f6?s=96&d=mm&r=g","caption":"oliviere"},"sameAs":["http:\/\/www.motocrossmag.be"],"url":"https:\/\/fr.motocrossmag.be\/index.php\/author\/oliviere\/"}]}},"_links":{"self":[{"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/posts\/77765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/users\/932"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/comments?post=77765"}],"version-history":[{"count":0,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/posts\/77765\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/media\/12590"}],"wp:attachment":[{"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/media?parent=77765"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/categories?post=77765"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.motocrossmag.be\/index.php\/wp-json\/wp\/v2\/tags?post=77765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}